{"id":9267,"date":"2019-07-05T12:48:00","date_gmt":"2019-07-05T17:48:00","guid":{"rendered":"https:\/\/staging.holaamericanews.com\/?p=9267"},"modified":"2019-07-05T12:48:12","modified_gmt":"2019-07-05T17:48:12","slug":"dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines","status":"publish","type":"post","link":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/","title":{"rendered":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio"},"content":{"rendered":"<div id=\"holaa-3140067759\" class=\"holaa-before-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-300x37.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-696x86.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><p><span style=\"font-weight: 400;\">\u00bfAlguna vez has SO\u00d1ADO con ir de viaje a <\/span><b>Italia<\/b><span style=\"font-weight: 400;\">? Pues en su m\u00e1s reciente producci\u00f3n, Cirque Italia trae las ciudades italianas hasta ti mientras nuestro majestuoso velero navega de puerto en puerto\u2026 \u00a1No pierdas tu oportunidad de abordar en WEST DES MOINES, IA! \u00a1Nos vemos del 18 al 21 de julio!<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada a\u00f1o desde sus inicios en 2012, Cirque Italia se ha esforzado en llevar una experiencia \u00fanica a muchos de las maravillosas ciudades en los Estados Unidos. Esta temporada 2019 hemos decidido traer algunas de las ciudades italianas con nosotros. No necesitas viajar a Europa para conocer parte de la cultura de Italia\u2026 \u00a1Nosotros la traemos hasta TI!<\/span><\/p><div id=\"holaa-2474762140\" class=\"holaa-ad-inside-articles-2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.aap.org\/en\/patient-care\/lead-exposure\/lead-exposure-in-children\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Web Ad July #1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg 2560w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-300x75.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1024x256.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-768x192.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1536x384.jpg 1536w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-2048x512.jpg 2048w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-696x174.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1068x267.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1920x480.jpg 1920w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" width=\"600\" height=\"640\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">Entonces, \u00bfqu\u00e9 es exactamente lo que propone esta Aventura mar\u00edtima? Hemos transformado nuestro singular escenario acu\u00e1tico como la cubierta de un barco con la adici\u00f3n de espectaculares fuentes estilo Bellagio.\u00a0\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&lt;iframe width=&#8221;560&#8243; height=&#8221;315&#8243; src=&#8221;https:\/\/www.youtube.com\/embed\/HCglUs4TFE0&#8243; frameborder=&#8221;0&#8243; allow=&#8221;accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture&#8221; allowfullscreen&gt;&lt;\/iframe&gt;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">As\u00ed como Italia ofrece una amplia variedad de comidas, cultura y personajes; Cirque Italia se complace en presentar diversos actos y artistas de alrededor del mundo. No queremos revelar mucho, pero prep\u00e1rate para disfrutar de contorsionismo, magia, tiro con arco, trapecistas y la siempre emocionante Rueda de la Muerte.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada acto tendr\u00e1 como tema central, las caracter\u00edsticas fundamentales de los diferentes pueblos italianos que hemos decidido visitar en este viaje maravilloso. Por ejemplo, cuando lleguemos a Venecia, podr\u00e1s admirar la exquisita delicadeza de las m\u00e1scaras venecianas.<\/span><\/p><div id=\"holaa-1662548011\" class=\"holaa-ad-inside-articles holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/actionnetwork.org\/forms\/sign-up-for-progress-iowas-high-five\/\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"H5 Spanish 300 x 250 Progress Iowa\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/H5-Spanish-300-x-250-Progress-Iowa.png\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">Manuel Rebecchi, presidente y due\u00f1o de Cirque Italia, est\u00e1 verdaderamente orgulloso de su herencia y nacionalidad italianas y para \u00e9l es un privilegio compartir con la audiencia estadounidense sus ra\u00edces de manera divertida y original. Nuestra productora Chant\u00e9 DeMoustes ha visitado varias ciudades italianas y ha tratado de plasmar sus experiencias en la producci\u00f3n de esta temporada 2019.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cirque Italia contin\u00faa contribuyendo a la modernizaci\u00f3n de las artes circenses mediante una estricta e inviolable pol\u00edtica de NO Animales en el show.\u00a0<\/span><\/p><div id=\"holaa-1282604305\" class=\"holaa-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/300x250.jpg\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><span style=\"font-weight: 400;\">Para m\u00e1s informaci\u00f3n visita <\/span><a href=\"http:\/\/www.cirqueitalia.com\"><span style=\"font-weight: 400;\">www.cirqueitalia.com<\/span><\/a><span style=\"font-weight: 400;\"> y aseg\u00farate de chequear todas nuestras redes sociales.\u00a0<\/span><\/p>\n<p><b>Cuando: julio 18-21<\/b><\/p><div id=\"holaa-337495596\" class=\"holaa-content_2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><b>Donde: 101 Jordan Creek Pkwy, West Des Moines IA 50266<\/b><\/p>\n<p><b>En: Jordan Creek Town Center<\/b><\/p>\n<p><b>Cerca de: en el estacionamiento<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><b>\u00a1Bajo la impresionante carpa BLANCA y AZUL!<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b> \u00a0 \u00a0 julio 18 \u2013 jueves: 7:30pm<\/b><\/li>\n<li><b> \u00a0 \u00a0 julio 19 \u2013 viernes: 7:30pm<\/b><\/li>\n<li><b> \u00a0 \u00a0 julio 20 &#8211; s\u00e1bado: 1:30pm, 4:30pm &amp; 7:30pm<\/b><\/li>\n<li><b> \u00a0 \u00a0 julio 21 \u2013 domingo: 1:30pm, 4:30pm &amp; 7:30pm<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><b>Horario de la Taquilla:<\/b><\/p>\n<p><i><span style=\"font-weight: 400;\">La taquilla abre los martes a las 10:00 AM en la semana del show<\/span><\/i><\/p>\n<p><span style=\"font-weight: 400;\">Cuando no hay show: 10am \u2013 6pm<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cuando hay show: 10am \u2013 10pm<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Puede comprar sus boletos en la p\u00e1gina cirqueitalia.com\/tickets o por tel\u00e9fono (941) 704-8572. Tambi\u00e9n respondemos SMS.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Non vediamo l&#8217;ora di vedervi allo spettacolo! Let Your Imagination Wander&#8230;and come DIVE into the Magical world of CIRQUE ITALIA.\u00a0\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<div id=\"holaa-1158234879\" class=\"holaa-after-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez has SO\u00d1ADO con ir de viaje a Italia? Pues en su m\u00e1s reciente producci\u00f3n, Cirque Italia trae las ciudades italianas hasta ti mientras nuestro majestuoso velero navega de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":9268,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[27,408,1358,11],"tags":[1259,259],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"{:en}Have you ever DREAMED of visiting ITALY? Well in it\u2019s NEWEST production Cirque Italia is bringing the towns of Italy to you as our majestic ship sails from port to port\u2026\u2026\u2026Don\u2019t miss your chance to board WEST DES MOINES, IA! We\u2019ll see you July 18-21! Each\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hola America News\"\/>\n\t<meta name=\"google-site-verification\" content=\"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"{:en}Hola America News{:}{:es}Hola America News{:}\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News\" \/>\n\t\t<meta property=\"og:description\" content=\"{:en}Have you ever DREAMED of visiting ITALY? Well in it\u2019s NEWEST production Cirque Italia is bringing the towns of Italy to you as our majestic ship sails from port to port\u2026\u2026\u2026Don\u2019t miss your chance to board WEST DES MOINES, IA! We\u2019ll see you July 18-21! Each\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2019\/07\/bubble-act-resized-2-Copy.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2019\/07\/bubble-act-resized-2-Copy.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-07-05T17:48:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-07-05T17:48:12+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News\" \/>\n\t\t<meta name=\"twitter:description\" content=\"{:en}Have you ever DREAMED of visiting ITALY? Well in it\u2019s NEWEST production Cirque Italia is bringing the towns of Italy to you as our majestic ship sails from port to port\u2026\u2026\u2026Don\u2019t miss your chance to board WEST DES MOINES, IA! We\u2019ll see you July 18-21! Each\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2019\/07\/bubble-act-resized-2-Copy.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#article\",\"name\":\"El M\\u00e1gico Mundo del Circo Acu\\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News\",\"headline\":\"El M\\u00e1gico Mundo del Circo Acu\\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio\",\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/bubble-act-resized-2-Copy.jpg\",\"width\":1080,\"height\":720},\"datePublished\":\"2019-07-05T12:48:00-05:00\",\"dateModified\":\"2019-07-05T12:48:12-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#webpage\"},\"articleSection\":\"Business, Culture, Festivals, Hola Iowa, Cirque Italia, West Des Moines, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"position\":2,\"name\":\"Latest News\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"position\":3,\"name\":\"Hola Iowa\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#listItem\",\"name\":\"El M\\u00e1gico Mundo del Circo Acu\\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#listItem\",\"position\":4,\"name\":\"El M\\u00e1gico Mundo del Circo Acu\\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\",\"name\":\"Hola America News\",\"description\":\"The Midwest's Latino News Source\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"telephone\":\"+13097215693\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HolaAmerica-News-web-logo.png\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#organizationLogo\",\"width\":1000,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/holaamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/#author\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/\",\"name\":\"Hola America News\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d1c582bb271b69c302058f9a55f4953?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Hola America News\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#webpage\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/\",\"name\":\"El M\\u00e1gico Mundo del Circo Acu\\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News\",\"description\":\"{:en}Have you ever DREAMED of visiting ITALY? Well in it\\u2019s NEWEST production Cirque Italia is bringing the towns of Italy to you as our majestic ship sails from port to port\\u2026\\u2026\\u2026Don\\u2019t miss your chance to board WEST DES MOINES, IA! We\\u2019ll see you July 18-21! Each\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/bubble-act-resized-2-Copy.jpg\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#mainImage\",\"width\":1080,\"height\":720},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\\\/#mainImage\"},\"datePublished\":\"2019-07-05T12:48:00-05:00\",\"dateModified\":\"2019-07-05T12:48:12-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"name\":\"{:en}Hola America News{:}{:es}Hola America News{:}\",\"description\":\"The Midwest's Latino News Source\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News","description":"{:en}Have you ever DREAMED of visiting ITALY? Well in it\u2019s NEWEST production Cirque Italia is bringing the towns of Italy to you as our majestic ship sails from port to port\u2026\u2026\u2026Don\u2019t miss your chance to board WEST DES MOINES, IA! We\u2019ll see you July 18-21! Each","canonical_url":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#article","name":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News","headline":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio","author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/#author"},"publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2019\/07\/bubble-act-resized-2-Copy.jpg","width":1080,"height":720},"datePublished":"2019-07-05T12:48:00-05:00","dateModified":"2019-07-05T12:48:12-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#webpage"},"isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#webpage"},"articleSection":"Business, Culture, Festivals, Hola Iowa, Cirque Italia, West Des Moines, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/holaamericanews.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","position":2,"name":"Latest News","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","position":3,"name":"Hola Iowa","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#listItem","name":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#listItem","position":4,"name":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio","previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"}}]},{"@type":"Organization","@id":"https:\/\/holaamericanews.com\/es\/#organization","name":"Hola America News","description":"The Midwest's Latino News Source","url":"https:\/\/holaamericanews.com\/es\/","telephone":"+13097215693","logo":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/03\/HolaAmerica-News-web-logo.png","@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#organizationLogo","width":1000,"height":800},"image":{"@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/holaamerica"]},{"@type":"Person","@id":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/#author","url":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/","name":"Hola America News","image":{"@type":"ImageObject","@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6d1c582bb271b69c302058f9a55f4953?s=96&d=mm&r=g","width":96,"height":96,"caption":"Hola America News"}},{"@type":"WebPage","@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#webpage","url":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/","name":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News","description":"{:en}Have you ever DREAMED of visiting ITALY? Well in it\u2019s NEWEST production Cirque Italia is bringing the towns of Italy to you as our majestic ship sails from port to port\u2026\u2026\u2026Don\u2019t miss your chance to board WEST DES MOINES, IA! We\u2019ll see you July 18-21! Each","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#breadcrumblist"},"author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/#author"},"creator":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2019\/07\/bubble-act-resized-2-Copy.jpg","@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#mainImage","width":1080,"height":720},"primaryImageOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/#mainImage"},"datePublished":"2019-07-05T12:48:00-05:00","dateModified":"2019-07-05T12:48:12-05:00"},{"@type":"WebSite","@id":"https:\/\/holaamericanews.com\/es\/#website","url":"https:\/\/holaamericanews.com\/es\/","name":"{:en}Hola America News{:}{:es}Hola America News{:}","description":"The Midwest's Latino News Source","inLanguage":"es-ES","publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"{:en}Hola America News{:}{:es}Hola America News{:}","og:type":"article","og:title":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News","og:description":"{:en}Have you ever DREAMED of visiting ITALY? Well in it\u2019s NEWEST production Cirque Italia is bringing the towns of Italy to you as our majestic ship sails from port to port\u2026\u2026\u2026Don\u2019t miss your chance to board WEST DES MOINES, IA! We\u2019ll see you July 18-21! Each","og:url":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/","og:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2019\/07\/bubble-act-resized-2-Copy.jpg","og:image:secure_url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2019\/07\/bubble-act-resized-2-Copy.jpg","og:image:width":1080,"og:image:height":720,"article:published_time":"2019-07-05T17:48:00+00:00","article:modified_time":"2019-07-05T17:48:12+00:00","article:publisher":"https:\/\/www.facebook.com\/HolaAmericaNews","twitter:card":"summary","twitter:site":"@HolaAmericaNews","twitter:title":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio | Hola America News","twitter:description":"{:en}Have you ever DREAMED of visiting ITALY? Well in it\u2019s NEWEST production Cirque Italia is bringing the towns of Italy to you as our majestic ship sails from port to port\u2026\u2026\u2026Don\u2019t miss your chance to board WEST DES MOINES, IA! We\u2019ll see you July 18-21! Each","twitter:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2019\/07\/bubble-act-resized-2-Copy.jpg"},"aioseo_meta_data":{"post_id":"9267","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":"","og_description":"","og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":"","og_article_tags":"","twitter_use_og":false,"twitter_card":"summary","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-03-28 18:47:15","updated":"2026-01-28 08:29:20","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/\" title=\"Latest News\">Latest News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/\" title=\"Hola Iowa\">Hola Iowa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/holaamericanews.com\/es"},{"label":"Latest News","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/"},{"label":"Hola Iowa","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/"},{"label":"El M\u00e1gico Mundo del Circo Acu\u00e1tico Cirque Italia llega a West Des Moines del 18-21 de Julio","link":"https:\/\/holaamericanews.com\/es\/dive-into-the-magical-world-of-cirque-italia-from-july-18-to-21-in-west-des-moines\/"}],"_links":{"self":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/9267"}],"collection":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/comments?post=9267"}],"version-history":[{"count":0,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/9267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media\/9268"}],"wp:attachment":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media?parent=9267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/categories?post=9267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/tags?post=9267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}