{"id":5201,"date":"2016-09-03T21:59:59","date_gmt":"2016-09-04T02:59:59","guid":{"rendered":"http:\/\/staging.holaamericanews.com\/?p=5201"},"modified":"2016-09-03T22:31:14","modified_gmt":"2016-09-04T03:31:14","slug":"los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa","status":"publish","type":"post","link":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/","title":{"rendered":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa"},"content":{"rendered":"<div id=\"holaa-483610276\" class=\"holaa-before-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-300x37.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-696x86.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><p>&#8220;Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.&#8221;<br \/>\n&#8211; Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa<\/p>\n<div style=\"width: 696px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-5201-1\" width=\"696\" height=\"392\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/tigres1.mp4?_=1\" \/><a href=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/tigres1.mp4\">https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/tigres1.mp4<\/a><\/video><\/div>\n\n<p><strong>Video por Adela Adeyini-Williams<\/strong><\/p><div id=\"holaa-1160476126\" class=\"holaa-ad-inside-articles-2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.aap.org\/en\/patient-care\/lead-exposure\/lead-exposure-in-children\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Web Ad July #1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg 2560w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-300x75.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1024x256.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-768x192.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1536x384.jpg 1536w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-2048x512.jpg 2048w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-696x174.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1068x267.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1920x480.jpg 1920w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" width=\"600\" height=\"640\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<div id=\"holaa-2240053248\" class=\"holaa-after-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>&#8220;Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5206,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[408,6,67,10,11,12,13,51],"tags":[485,225,660],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":false,"content":false,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"&quot;Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.&quot; - Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hola America News\"\/>\n\t<meta name=\"google-site-verification\" content=\"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"{:en}Hola America News{:}{:es}Hola America News{:}\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News\" \/>\n\t\t<meta property=\"og:description\" content=\"&quot;Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.&quot; - Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/IMG_20160903_1152281.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/IMG_20160903_1152281.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1393\" \/>\n\t\t<meta property=\"og:image:height\" content=\"1026\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2016-09-04T02:59:59+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2016-09-04T03:31:14+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News\" \/>\n\t\t<meta name=\"twitter:description\" content=\"&quot;Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.&quot; - Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/IMG_20160903_1152281.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#article\",\"name\":\"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News\",\"headline\":\"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa\",\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/IMG_20160903_1152281.jpg\",\"width\":1393,\"height\":1026},\"datePublished\":\"2016-09-03T21:59:59-05:00\",\"dateModified\":\"2016-09-03T22:31:14-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#webpage\"},\"articleSection\":\"Culture, Editorials, Gallery, Hola Illinois, Hola Iowa, Immigration, Latest News &amp; Features, Politics, Hillary Clinton, Hola Iowa, Los Tigres Del Norte, Video, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"position\":2,\"name\":\"Latest News\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/editorials\\\/#listItem\",\"name\":\"Editorials\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/editorials\\\/#listItem\",\"position\":3,\"name\":\"Editorials\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/editorials\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#listItem\",\"name\":\"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#listItem\",\"position\":4,\"name\":\"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/editorials\\\/#listItem\",\"name\":\"Editorials\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\",\"name\":\"Hola America News\",\"description\":\"The Midwest's Latino News Source\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"telephone\":\"+13097215693\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HolaAmerica-News-web-logo.png\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#organizationLogo\",\"width\":1000,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/holaamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/#author\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/\",\"name\":\"Hola America News\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6d1c582bb271b69c302058f9a55f4953?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Hola America News\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#webpage\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/\",\"name\":\"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News\",\"description\":\"\\\"Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.\\\" - Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-america-news\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/IMG_20160903_1152281.jpg\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#mainImage\",\"width\":1393,\"height\":1026},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\\\/#mainImage\"},\"datePublished\":\"2016-09-03T21:59:59-05:00\",\"dateModified\":\"2016-09-03T22:31:14-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"name\":\"{:en}Hola America News{:}{:es}Hola America News{:}\",\"description\":\"The Midwest's Latino News Source\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News","description":"\"Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.\" - Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa","canonical_url":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#article","name":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News","headline":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa","author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/#author"},"publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/IMG_20160903_1152281.jpg","width":1393,"height":1026},"datePublished":"2016-09-03T21:59:59-05:00","dateModified":"2016-09-03T22:31:14-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#webpage"},"isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#webpage"},"articleSection":"Culture, Editorials, Gallery, Hola Illinois, Hola Iowa, Immigration, Latest News &amp; Features, Politics, Hillary Clinton, Hola Iowa, Los Tigres Del Norte, Video, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/holaamericanews.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","position":2,"name":"Latest News","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/editorials\/#listItem","name":"Editorials"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/editorials\/#listItem","position":3,"name":"Editorials","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/editorials\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#listItem","name":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#listItem","position":4,"name":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa","previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/editorials\/#listItem","name":"Editorials"}}]},{"@type":"Organization","@id":"https:\/\/holaamericanews.com\/es\/#organization","name":"Hola America News","description":"The Midwest's Latino News Source","url":"https:\/\/holaamericanews.com\/es\/","telephone":"+13097215693","logo":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/03\/HolaAmerica-News-web-logo.png","@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#organizationLogo","width":1000,"height":800},"image":{"@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/holaamerica"]},{"@type":"Person","@id":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/#author","url":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/","name":"Hola America News","image":{"@type":"ImageObject","@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/6d1c582bb271b69c302058f9a55f4953?s=96&d=mm&r=g","width":96,"height":96,"caption":"Hola America News"}},{"@type":"WebPage","@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#webpage","url":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/","name":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News","description":"\"Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.\" - Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#breadcrumblist"},"author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/#author"},"creator":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-america-news\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/IMG_20160903_1152281.jpg","@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#mainImage","width":1393,"height":1026},"primaryImageOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/#mainImage"},"datePublished":"2016-09-03T21:59:59-05:00","dateModified":"2016-09-03T22:31:14-05:00"},{"@type":"WebSite","@id":"https:\/\/holaamericanews.com\/es\/#website","url":"https:\/\/holaamericanews.com\/es\/","name":"{:en}Hola America News{:}{:es}Hola America News{:}","description":"The Midwest's Latino News Source","inLanguage":"es-ES","publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"{:en}Hola America News{:}{:es}Hola America News{:}","og:type":"article","og:title":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News","og:description":"&quot;Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.&quot; - Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa","og:url":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/","og:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/IMG_20160903_1152281.jpg","og:image:secure_url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/IMG_20160903_1152281.jpg","og:image:width":1393,"og:image:height":1026,"article:published_time":"2016-09-04T02:59:59+00:00","article:modified_time":"2016-09-04T03:31:14+00:00","article:publisher":"https:\/\/www.facebook.com\/HolaAmericaNews","twitter:card":"summary","twitter:site":"@HolaAmericaNews","twitter:title":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa | Hola America News","twitter:description":"&quot;Ya estamos cansados que nos llamen violadores y criminales y es por eso que desde hoy sus amigos los Tigres del Norte respaldamos y apoyamos a Hillary Clinton para que sea presidente. Los invitamos a votar por ella al igual que nosotros.&quot; - Los Tigres del Norte apoyan a Hillary Clinton para presidente desde Iowa","twitter:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2016\/09\/IMG_20160903_1152281.jpg"},"aioseo_meta_data":{"post_id":"5201","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-03-28 18:11:51","updated":"2026-01-28 07:46:19","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/\" title=\"Latest News\">Latest News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/editorials\/\" title=\"Editorials\">Editorials<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLos Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/holaamericanews.com\/es"},{"label":"Latest News","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/"},{"label":"Editorials","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/editorials\/"},{"label":"Los Tigres del Norte declaran su apoyo a Hillary Clinton desde Iowa","link":"https:\/\/holaamericanews.com\/es\/los-tigres-del-norte-declaran-su-apoyo-a-hillary-clinton-desde-iowa\/"}],"_links":{"self":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/5201"}],"collection":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/comments?post=5201"}],"version-history":[{"count":0,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/5201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media\/5206"}],"wp:attachment":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media?parent=5201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/categories?post=5201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/tags?post=5201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}