{"id":35776,"date":"2026-03-09T11:18:41","date_gmt":"2026-03-09T16:18:41","guid":{"rendered":"https:\/\/holaamericanews.com\/?p=35776"},"modified":"2026-03-09T11:22:00","modified_gmt":"2026-03-09T16:22:00","slug":"sioux-city-iowa-debates-major-cuts-to-public-library-budget","status":"publish","type":"post","link":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/","title":{"rendered":"Sioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\u00fablica"},"content":{"rendered":"<div id=\"holaa-2246277243\" class=\"holaa-before-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-300x37.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-696x86.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><p><b>Por <\/b><a href=\"https:\/\/www.iowapublicradio.org\/people\/sheila-brummer\" target=\"_blank\" rel=\"nofollow noopener\"><b>Sheila Brummer<\/b><\/a><b>, <a href=\"https:\/\/www.iowapublicradio.org\/ipr-news\/2026-03-04\/sioux-city-library-budget-cuts\" target=\"_blank\" rel=\"noopener\">Iowa Public Radio <\/a><\/b><\/p>\n<h3><span style=\"font-weight: 400;\">L\u00edderes de Sioux City eval\u00faan recortes de aproximadamente $1 mill\u00f3n, o el 25 %, del presupuesto del sistema de bibliotecas p\u00fablicas como parte de las conversaciones en curso sobre el presupuesto municipal. La directora de la biblioteca advierte que las reducciones afectar\u00edan programas y personal.<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">La moral en la <\/span><a href=\"https:\/\/www.siouxcitylibrary.org\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400;\">Biblioteca P\u00fablica de Sioux City<\/span><\/a><span style=\"font-weight: 400;\"> est\u00e1 \u201ccasi en cero\u201d, seg\u00fan la directora de la biblioteca, Helen Rigdon.<\/span><\/p><div id=\"holaa-2179096399\" class=\"holaa-ad-inside-articles-2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.aap.org\/en\/patient-care\/lead-exposure\/lead-exposure-in-children\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Web Ad July #1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg 2560w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-300x75.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1024x256.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-768x192.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1536x384.jpg 1536w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-2048x512.jpg 2048w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-696x174.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1068x267.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1920x480.jpg 1920w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" width=\"600\" height=\"640\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">\u201cEllos sienten, y yo tambi\u00e9n, que algunos miembros del consejo municipal no valoran lo que la biblioteca aporta a la ciudad\u201d, dijo Rigdon.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Mientras los funcionarios de Sioux City contin\u00faan las conversaciones sobre el presupuesto, el sistema de bibliotecas podr\u00eda perder alrededor de $1 mill\u00f3n, una cuarta parte de su presupuesto anual de casi $4 millones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Rigdon dijo que una reducci\u00f3n de ese tipo ser\u00eda devastadora.<\/span><\/p>\n<figure id=\"attachment_35782\" aria-describedby=\"caption-attachment-35782\" style=\"width: 200px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-35782 size-medium\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-22-2-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-22-2-200x300.jpg 200w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-22-2-683x1024.jpg 683w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-22-2-768x1152.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-22-2-696x1044.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-22-2.jpg 880w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><figcaption id=\"caption-attachment-35782\" class=\"wp-caption-text\">Foto cortes\u00eda de la Ciudad de Sioux City. Helen Rigdon es la directora de la Biblioteca P\u00fablica de Sioux City.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">\u201cSolo esperamos que el consejo municipal reconozca lo que aportamos a la comunidad\u201d, dijo. \u201cPodemos resolver esto y no tiene por qu\u00e9 convertirse en un recorte tan perjudicial\u201d.<\/span><\/p><div id=\"holaa-1027642782\" class=\"holaa-ad-inside-articles holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/actionnetwork.org\/forms\/sign-up-for-progress-iowas-high-five\/\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"H5 Spanish 300 x 250 Progress Iowa\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/H5-Spanish-300-x-250-Progress-Iowa.png\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">El concejal municipal y exsenador estatal Rick Bertrand dijo que la discusi\u00f3n no se centra en eliminar servicios, sino en replantear c\u00f3mo se prestan.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cCada vez que se empieza a hablar de servicios p\u00fablicos, la gente se pone nerviosa\u201d, dijo Bertrand. \u201cPero esto es lo que hace una comunidad saludable: analizar c\u00f3mo maximizar los recursos para atender a m\u00e1s personas\u201d.<\/span><\/p><div id=\"holaa-2386497102\" class=\"holaa-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/300x250.jpg\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><span style=\"font-weight: 400;\">Bertrand dijo que favorece avanzar hacia bibliotecas comunitarias m\u00e1s peque\u00f1as, o \u201cpocket libraries\u201d, ubicadas en distintos puntos de la ciudad, con servicios como cafeter\u00edas o espacios comerciales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cDe nuevo, no tiene nada de malo que el consejo o la comunidad comiencen a preguntarse: \u2018\u00bfNecesitamos un espacio tan grande? \u00bfRealmente se utiliza el espacio del centro? \u00bfLa gente se siente c\u00f3moda?\u2019\u201d, dijo. \u201cTodas estas son conversaciones saludables sobre c\u00f3mo podemos servir mejor a la comunidad\u201d.<\/span><\/p><div id=\"holaa-223058280\" class=\"holaa-content_2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<figure id=\"attachment_35780\" aria-describedby=\"caption-attachment-35780\" style=\"width: 880px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35780\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-23.jpg\" alt=\"\" width=\"880\" height=\"653\" srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-23.jpg 880w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-23-300x223.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-23-768x570.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-23-485x360.jpg 485w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-23-696x516.jpg 696w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/><figcaption id=\"caption-attachment-35780\" class=\"wp-caption-text\">Sheila Brummer \/ Iowa Public Radio. La biblioteca Aalfs Downtown de Sioux City abri\u00f3 en 1990. El p\u00fablico seleccion\u00f3 *The River We Remember* para el programa Sioux City Reads de este a\u00f1o, una iniciativa comunitaria que incluye debates y eventos relacionados.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Rigdon dijo que la idea de reestructurar el sistema de bibliotecas surgi\u00f3 por primera vez en septiembre, cuando l\u00edderes de la ciudad se acercaron a ella con lo que describi\u00f3 como un plan conceptual generado por ChatGPT.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cEn la parte superior dec\u00eda \u2018plan conceptual de biblioteca comunitaria para una ciudad de 85,000 residentes\u2019\u201d, dijo Rigdon. \u201cNo s\u00e9 qu\u00e9 par\u00e1metros se utilizaron, pero inclu\u00eda un presupuesto de $2 millones\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Rigdon, quien planea jubilarse a finales de abril, dijo que la junta de la biblioteca quer\u00eda esperar a que llegara un nuevo director antes de emprender cualquier cambio importante.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se\u00f1al\u00f3 que los l\u00edderes de la ciudad le pidieron presentar una propuesta de presupuesto sin aumentos, lo cual hizo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Pero Rigdon explic\u00f3 que en la d\u00e9cada de 1980 Sioux City se vio obligada a cerrar varias sucursales para reducir costos. Actualmente, la biblioteca opera una sede principal en el centro y las sucursales de Morningside y Perry Creek, en los lados este y norte de la ciudad.<\/span><\/p>\n<figure id=\"attachment_35781\" aria-describedby=\"caption-attachment-35781\" style=\"width: 880px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-35781\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-24.jpg\" alt=\"\" width=\"880\" height=\"610\" srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-24.jpg 880w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-24-300x208.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-24-768x532.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-24-218x150.jpg 218w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-24-696x482.jpg 696w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/><figcaption id=\"caption-attachment-35781\" class=\"wp-caption-text\">Sheila Brummer \/ Iowa Public Radio. La sucursal Perry Creek de la biblioteca est\u00e1 ubicada en el lado norte de Sioux City. Ofrece una hora semanal de cuentos para ni\u00f1os. Tambi\u00e9n hay otra sucursal en el lado este de la ciudad.<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">Rigdon dijo que la biblioteca ya cuenta con uno de los equipos de personal de tiempo completo m\u00e1s peque\u00f1os del estado para una ciudad de su tama\u00f1o. La reducci\u00f3n propuesta recortar\u00eda los puestos de 31 a 25.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cYa tenemos el segundo n\u00famero m\u00e1s bajo de FTE [equivalentes de tiempo completo] en el estado, pero somos la cuarta ciudad m\u00e1s grande\u201d, dijo Rigdon. \u201cEs casi imposible. No habr\u00eda margen para la programaci\u00f3n, el procesamiento de materiales ni para las tareas que hacen que una biblioteca funcione\u201d.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una reuni\u00f3n final sobre el presupuesto est\u00e1 programada para el 18 de marzo, y Rigdon dijo que intenta mantenerse optimista.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cMe digo a m\u00ed misma que es solo un obst\u00e1culo en el camino y que se resolver\u00e1\u201d, dijo. \u201cPero luego me enojo un poco, aunque trato de que ese no sea el sentimiento que prevalezca\u201d.<\/span><\/p>\n<hr \/>\n<p class=\"p1\"><b>Mant\u00e9ngase informado con historias que importan: visite <\/b><a href=\"http:\/\/holaamericanews.com\/\"><b>HolaAmericaNews.com<\/b><\/a><b> para conocer las \u00faltimas noticias, cultura y actualizaciones de la comunidad.<\/b><b><\/b><\/p>\n<div id=\"holaa-1665569668\" class=\"holaa-after-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Por Sheila Brummer, Iowa Public Radio L\u00edderes de Sioux City eval\u00faan recortes de aproximadamente $1 mill\u00f3n, o el 25 %, del presupuesto del sistema de bibliotecas p\u00fablicas como parte de [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":35778,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[11],"tags":[530,16537],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hola Iowa\"\/>\n\t<meta name=\"google-site-verification\" content=\"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"{:en}Hola America News{:}{:es}Hola America News{:}\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sioux City library budget cuts debated in Iowa\" \/>\n\t\t<meta property=\"og:description\" content=\"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-21-1.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-21-1.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"880\" \/>\n\t\t<meta property=\"og:image:height\" content=\"631\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-03-09T16:18:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-09T16:22:00+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sioux City library budget cuts debated in Iowa\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-21-1.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#article\",\"name\":\"Sioux City library budget cuts debated in Iowa\",\"headline\":\"Sioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\\u00fablica\",\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/download-21-1.jpg\",\"width\":880,\"height\":631,\"caption\":\"Sheila Brummer \\\/ Iowa Public Radio. The downtown branch of the Sioux City Public Library features a large children's section and is celebrating Dr. Seuss Week from March 2-6.\"},\"datePublished\":\"2026-03-09T11:18:41-05:00\",\"dateModified\":\"2026-03-09T11:22:00-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#webpage\"},\"articleSection\":\"Hola Iowa, Sioux City, Sioux City Public Library, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"position\":2,\"name\":\"Latest News\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"position\":3,\"name\":\"Hola Iowa\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#listItem\",\"name\":\"Sioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\\u00fablica\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#listItem\",\"position\":4,\"name\":\"Sioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\\u00fablica\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\",\"name\":\"Hola America News\",\"description\":\"The Midwest's Latino News Source\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"telephone\":\"+13097215693\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HolaAmerica-News-web-logo.png\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#organizationLogo\",\"width\":1000,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/holaamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/\",\"name\":\"Hola Iowa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Hola Iowa\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#webpage\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/\",\"name\":\"Sioux City library budget cuts debated in Iowa\",\"description\":\"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/download-21-1.jpg\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#mainImage\",\"width\":880,\"height\":631,\"caption\":\"Sheila Brummer \\\/ Iowa Public Radio. The downtown branch of the Sioux City Public Library features a large children's section and is celebrating Dr. Seuss Week from March 2-6.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\\\/#mainImage\"},\"datePublished\":\"2026-03-09T11:18:41-05:00\",\"dateModified\":\"2026-03-09T11:22:00-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"name\":\"{:en}Hola America News{:}{:es}Hola America News{:}\",\"description\":\"The Midwest's Latino News Source\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sioux City library budget cuts debated in Iowa","description":"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.","canonical_url":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#article","name":"Sioux City library budget cuts debated in Iowa","headline":"Sioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\u00fablica","author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-21-1.jpg","width":880,"height":631,"caption":"Sheila Brummer \/ Iowa Public Radio. The downtown branch of the Sioux City Public Library features a large children's section and is celebrating Dr. Seuss Week from March 2-6."},"datePublished":"2026-03-09T11:18:41-05:00","dateModified":"2026-03-09T11:22:00-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#webpage"},"isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#webpage"},"articleSection":"Hola Iowa, Sioux City, Sioux City Public Library, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/holaamericanews.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","position":2,"name":"Latest News","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","position":3,"name":"Hola Iowa","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#listItem","name":"Sioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\u00fablica"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#listItem","position":4,"name":"Sioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\u00fablica","previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"}}]},{"@type":"Organization","@id":"https:\/\/holaamericanews.com\/es\/#organization","name":"Hola America News","description":"The Midwest's Latino News Source","url":"https:\/\/holaamericanews.com\/es\/","telephone":"+13097215693","logo":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/03\/HolaAmerica-News-web-logo.png","@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#organizationLogo","width":1000,"height":800},"image":{"@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/holaamerica"]},{"@type":"Person","@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author","url":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/","name":"Hola Iowa","image":{"@type":"ImageObject","@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Hola Iowa"}},{"@type":"WebPage","@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#webpage","url":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/","name":"Sioux City library budget cuts debated in Iowa","description":"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#breadcrumblist"},"author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"creator":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-21-1.jpg","@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#mainImage","width":880,"height":631,"caption":"Sheila Brummer \/ Iowa Public Radio. The downtown branch of the Sioux City Public Library features a large children's section and is celebrating Dr. Seuss Week from March 2-6."},"primaryImageOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/#mainImage"},"datePublished":"2026-03-09T11:18:41-05:00","dateModified":"2026-03-09T11:22:00-05:00"},{"@type":"WebSite","@id":"https:\/\/holaamericanews.com\/es\/#website","url":"https:\/\/holaamericanews.com\/es\/","name":"{:en}Hola America News{:}{:es}Hola America News{:}","description":"The Midwest's Latino News Source","inLanguage":"es-ES","publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"{:en}Hola America News{:}{:es}Hola America News{:}","og:type":"article","og:title":"Sioux City library budget cuts debated in Iowa","og:description":"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.","og:url":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/","og:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-21-1.jpg","og:image:secure_url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-21-1.jpg","og:image:width":880,"og:image:height":631,"article:published_time":"2026-03-09T16:18:41+00:00","article:modified_time":"2026-03-09T16:22:00+00:00","article:publisher":"https:\/\/www.facebook.com\/HolaAmericaNews","twitter:card":"summary","twitter:site":"@HolaAmericaNews","twitter:title":"Sioux City library budget cuts debated in Iowa","twitter:description":"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.","twitter:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/03\/download-21-1.jpg"},"aioseo_meta_data":{"post_id":"35776","title":"Sioux City library budget cuts debated in Iowa","description":"Sioux City library budget cuts could reduce staffing, programs and services as city leaders weigh a $1 million reduction.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-03-09 16:00:54","updated":"2026-03-09 16:25:21","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/\" title=\"Latest News\">Latest News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/\" title=\"Hola Iowa\">Hola Iowa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\u00fablica\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/holaamericanews.com\/es"},{"label":"Latest News","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/"},{"label":"Hola Iowa","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/"},{"label":"Sioux City, Iowa debate recortes significativos al presupuesto de la biblioteca p\u00fablica","link":"https:\/\/holaamericanews.com\/es\/sioux-city-iowa-debates-major-cuts-to-public-library-budget\/"}],"_links":{"self":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/35776"}],"collection":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/comments?post=35776"}],"version-history":[{"count":0,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/35776\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media\/35778"}],"wp:attachment":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media?parent=35776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/categories?post=35776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/tags?post=35776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}