{"id":29887,"date":"2025-04-11T11:16:50","date_gmt":"2025-04-11T16:16:50","guid":{"rendered":"https:\/\/holaamericanews.com\/?p=29887"},"modified":"2025-04-11T11:16:50","modified_gmt":"2025-04-11T16:16:50","slug":"iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk","status":"publish","type":"post","link":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/","title":{"rendered":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12"},"content":{"rendered":"<div id=\"holaa-3001367626\" class=\"holaa-before-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-300x37.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-696x86.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><p><strong>Por <a href=\"https:\/\/www.iowapublicradio.org\/people\/katarina-sostaric\">Katarina Sostaric,\u00a0<\/a>Iowa Public Radio<\/strong><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Iowa-<\/strong>Los republicanos de la C\u00e1mara de Representantes de Iowa aprobaron el martes un aumento del 2% para<a href=\"https:\/\/www.legis.iowa.gov\/legislation\/BillBook?ga=91&amp;ba=SF167\"> la financiaci\u00f3n<\/a> por alumno del K-12, enviando el proyecto de ley a la oficina de la gobernadora para su firma m\u00e1s de dos meses despu\u00e9s de la fecha l\u00edmite para decidir la financiaci\u00f3n de la<a href=\"https:\/\/holaamericanews.com\/ban-on-students-use-of-cellphones-during-class-time-heads-to-governors-desk\/\"> educaci\u00f3n.<\/a><\/span><\/p><div id=\"holaa-3402735732\" class=\"holaa-ad-inside-articles-2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.aap.org\/en\/patient-care\/lead-exposure\/lead-exposure-in-children\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Web Ad July #1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg 2560w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-300x75.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1024x256.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-768x192.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1536x384.jpg 1536w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-2048x512.jpg 2048w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-696x174.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1068x267.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1920x480.jpg 1920w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" width=\"600\" height=\"640\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">El gasto del estado en la financiaci\u00f3n de la escuela por alumno aumentar\u00e1 en 162 d\u00f3lares a casi 7,988 d\u00f3lares por estudiante para las escuelas p\u00fablicas, escuelas charter y cuentas de ahorro educativo para la matr\u00edcula de la escuela privada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Partido Republicano de la C\u00e1mara propuso un aumento del 2.25% m\u00e1s fondos adicionales, pero finalmente acordaron el aumento del 2% propuesto por la gobernadora Kim Reynolds y los republicanos del Senado. El proyecto de ley final incluye un adicional de $ 5 millones para asuntos como el transporte y el reparto operativo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El representante Dan Gehlbach, R-Urbandale, dijo que el plan no es todo lo que la C\u00e1mara quer\u00eda, pero estaba orgulloso de que lucharon por m\u00e1s fondos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cBajo el liderazgo republicano en Iowa, hemos entregado los aumentos responsables y sostenibles a la educaci\u00f3n a\u00f1o tras a\u00f1o, con un enfoque en la estabilidad y el \u00e9xito del estudiante\u201d, dijo.<\/span><\/p><div id=\"holaa-1432382533\" class=\"holaa-ad-inside-articles holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/actionnetwork.org\/forms\/sign-up-for-progress-iowas-high-five\/\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"H5 Spanish 300 x 250 Progress Iowa\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/H5-Spanish-300-x-250-Progress-Iowa.png\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">Los dem\u00f3cratas criticaron el plan de financiaci\u00f3n como demasiado peque\u00f1o, demasiado tarde. El representante Heather Matson, D-Ankeny, dijo que el aumento del 2% no es suficiente para mantenerse al d\u00eda con el aumento de los costos y para ayudar a las escuelas p\u00fablicas a prosperar.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cNo nos pondr\u00e1 en el camino de ser el n\u00famero uno en la educaci\u00f3n de nuevo\u201d, dijo. \u201cMantiene a nuestras escuelas p\u00fablicas en modo de supervivencia. Simplemente no nos lleva a donde tenemos que ir\u201d.<\/span><\/p><div id=\"holaa-1914043468\" class=\"holaa-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/300x250.jpg\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><span style=\"font-weight: 400;\">Gehlbach dijo que el aumento asciende a $ 105.9 millones en dinero nuevo para las escuelas p\u00fablicas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los republicanos del Senado dijo que el aumento total para las escuelas p\u00fablicas es de $ 127.8 millones, con $ 105.9 millones procedentes del fondo general del estado y $ 21.9 millones de un fondo de reserva.<\/span><\/p><div id=\"holaa-4006289831\" class=\"holaa-content_2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><span style=\"font-weight: 400;\">Dijeron que la adici\u00f3n de los casi $ 97 millones de aumento para los estudiantes de escuelas privadas y $ 14.5 millones de aumento para las escuelas charter trae el nuevo gasto total en educaci\u00f3n K-12 a unos $ 240 millones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para el pr\u00f3ximo a\u00f1o escolar, el costo total de las cuentas de ahorro para la educaci\u00f3n se espera que sea de alrededor de $ 315 millones, como el l\u00edmite de ingresos para los participantes se eliminar\u00e1. Seg\u00fan los republicanos del Senado, el gasto total del Estado en educaci\u00f3n primaria y secundaria con el proyecto de ley aprobado el martes ascender\u00eda a unos 4,200 millones de d\u00f3lares.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Joshua Brown, presidente de la Asociaci\u00f3n de Educaci\u00f3n del Estado de Iowa, dijo que un aumento del 2% pone en peligro las oportunidades de los estudiantes. Dijo que un aumento del 5% es necesario para tener clases manejables y contratar y retener a los maestros y personal de apoyo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u201cSi los l\u00edderes estatales creen que el gasto de m\u00e1s de $ 1 mil millones en los pr\u00f3ximos tres a\u00f1os en vales de escuelas privadas, que sirven s\u00f3lo una fracci\u00f3n de nuestros estudiantes, es una buena idea, entonces el aumento de la financiaci\u00f3n para la mayor\u00eda de nuestros estudiantes en las escuelas p\u00fablicas tambi\u00e9n debe ser su prioridad\u201d, dijo Brown.<\/span><\/p>\n<div id=\"holaa-2557906685\" class=\"holaa-after-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Por Katarina Sostaric,\u00a0Iowa Public Radio Iowa-Los republicanos de la C\u00e1mara de Representantes de Iowa aprobaron el martes un aumento del 2% para la financiaci\u00f3n por alumno del K-12, enviando el [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":29889,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[50,11,8373,51],"tags":[101,2603,375],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\u2019s desk for her signature more\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hola Iowa\"\/>\n\t<meta name=\"google-site-verification\" content=\"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"{:en}Hola America News{:}{:es}Hola America News{:}\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12 | Hola America News\" \/>\n\t\t<meta property=\"og:description\" content=\"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\u2019s desk for her signature more\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/04\/1-3-e1744387996989.webp\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/04\/1-3-e1744387996989.webp\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-04-11T16:16:50+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-04-11T16:16:50+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12 | Hola America News\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\u2019s desk for her signature more\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/04\/1-3-e1744387996989.webp\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#article\",\"name\":\"La C\\u00e1mara de Representantes de Iowa env\\u00eda al gobernador un aumento del 2% en la financiaci\\u00f3n de las escuelas K-12 | Hola America News\",\"headline\":\"La C\\u00e1mara de Representantes de Iowa env\\u00eda al gobernador un aumento del 2% en la financiaci\\u00f3n de las escuelas K-12\",\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1-3-e1744387996989.webp\",\"width\":1200,\"height\":800,\"caption\":\"Madeleine Charis King\\nStudents in Ms. Davis' 2nd grade classroom enjoy quiet time after recess at Moore Elementary School, March 2025.\"},\"datePublished\":\"2025-04-11T11:16:50-05:00\",\"dateModified\":\"2025-04-11T11:16:50-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#webpage\"},\"articleSection\":\"Education, Hola Iowa, Iowa Governor's, Politics, Education, Iowa House Republicans, Iowa Politics, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"position\":2,\"name\":\"Latest News\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"position\":3,\"name\":\"Hola Iowa\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#listItem\",\"name\":\"La C\\u00e1mara de Representantes de Iowa env\\u00eda al gobernador un aumento del 2% en la financiaci\\u00f3n de las escuelas K-12\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#listItem\",\"position\":4,\"name\":\"La C\\u00e1mara de Representantes de Iowa env\\u00eda al gobernador un aumento del 2% en la financiaci\\u00f3n de las escuelas K-12\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\",\"name\":\"Hola America News\",\"description\":\"The Midwest's Latino News Source\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"telephone\":\"+13097215693\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HolaAmerica-News-web-logo.png\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#organizationLogo\",\"width\":1000,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/holaamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/\",\"name\":\"Hola Iowa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Hola Iowa\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#webpage\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/\",\"name\":\"La C\\u00e1mara de Representantes de Iowa env\\u00eda al gobernador un aumento del 2% en la financiaci\\u00f3n de las escuelas K-12 | Hola America News\",\"description\":\"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\\u2019s desk for her signature more\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/1-3-e1744387996989.webp\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#mainImage\",\"width\":1200,\"height\":800,\"caption\":\"Madeleine Charis King\\nStudents in Ms. Davis' 2nd grade classroom enjoy quiet time after recess at Moore Elementary School, March 2025.\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\\\/#mainImage\"},\"datePublished\":\"2025-04-11T11:16:50-05:00\",\"dateModified\":\"2025-04-11T11:16:50-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"name\":\"{:en}Hola America News{:}{:es}Hola America News{:}\",\"description\":\"The Midwest's Latino News Source\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12 | Hola America News","description":"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\u2019s desk for her signature more","canonical_url":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#article","name":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12 | Hola America News","headline":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12","author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/04\/1-3-e1744387996989.webp","width":1200,"height":800,"caption":"Madeleine Charis King\nStudents in Ms. Davis' 2nd grade classroom enjoy quiet time after recess at Moore Elementary School, March 2025."},"datePublished":"2025-04-11T11:16:50-05:00","dateModified":"2025-04-11T11:16:50-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#webpage"},"isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#webpage"},"articleSection":"Education, Hola Iowa, Iowa Governor's, Politics, Education, Iowa House Republicans, Iowa Politics, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/holaamericanews.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","position":2,"name":"Latest News","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","position":3,"name":"Hola Iowa","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#listItem","name":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#listItem","position":4,"name":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12","previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"}}]},{"@type":"Organization","@id":"https:\/\/holaamericanews.com\/es\/#organization","name":"Hola America News","description":"The Midwest's Latino News Source","url":"https:\/\/holaamericanews.com\/es\/","telephone":"+13097215693","logo":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/03\/HolaAmerica-News-web-logo.png","@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#organizationLogo","width":1000,"height":800},"image":{"@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/holaamerica"]},{"@type":"Person","@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author","url":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/","name":"Hola Iowa","image":{"@type":"ImageObject","@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Hola Iowa"}},{"@type":"WebPage","@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#webpage","url":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/","name":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12 | Hola America News","description":"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\u2019s desk for her signature more","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#breadcrumblist"},"author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"creator":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/04\/1-3-e1744387996989.webp","@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#mainImage","width":1200,"height":800,"caption":"Madeleine Charis King\nStudents in Ms. Davis' 2nd grade classroom enjoy quiet time after recess at Moore Elementary School, March 2025."},"primaryImageOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/#mainImage"},"datePublished":"2025-04-11T11:16:50-05:00","dateModified":"2025-04-11T11:16:50-05:00"},{"@type":"WebSite","@id":"https:\/\/holaamericanews.com\/es\/#website","url":"https:\/\/holaamericanews.com\/es\/","name":"{:en}Hola America News{:}{:es}Hola America News{:}","description":"The Midwest's Latino News Source","inLanguage":"es-ES","publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"{:en}Hola America News{:}{:es}Hola America News{:}","og:type":"article","og:title":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12 | Hola America News","og:description":"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\u2019s desk for her signature more","og:url":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/","og:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/04\/1-3-e1744387996989.webp","og:image:secure_url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/04\/1-3-e1744387996989.webp","og:image:width":1200,"og:image:height":800,"article:published_time":"2025-04-11T16:16:50+00:00","article:modified_time":"2025-04-11T16:16:50+00:00","article:publisher":"https:\/\/www.facebook.com\/HolaAmericaNews","twitter:card":"summary","twitter:site":"@HolaAmericaNews","twitter:title":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12 | Hola America News","twitter:description":"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\u2019s desk for her signature more","twitter:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/04\/1-3-e1744387996989.webp"},"aioseo_meta_data":{"post_id":"29887","title":null,"description":"Iowa House Republicans approved a 2% increase for K-12 per-pupil funding Tuesday, sending the bill to the governor\u2019s desk for her signature more","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-04-11 16:00:51","updated":"2026-01-28 12:11:19","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/\" title=\"Latest News\">Latest News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/\" title=\"Hola Iowa\">Hola Iowa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/holaamericanews.com\/es"},{"label":"Latest News","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/"},{"label":"Hola Iowa","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/"},{"label":"La C\u00e1mara de Representantes de Iowa env\u00eda al gobernador un aumento del 2% en la financiaci\u00f3n de las escuelas K-12","link":"https:\/\/holaamericanews.com\/es\/iowa-house-sends-2-k-12-school-funding-increase-to-governors-desk\/"}],"_links":{"self":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/29887"}],"collection":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/comments?post=29887"}],"version-history":[{"count":0,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/29887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media\/29889"}],"wp:attachment":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media?parent=29887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/categories?post=29887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/tags?post=29887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}