{"id":28906,"date":"2025-02-12T20:30:54","date_gmt":"2025-02-13T02:30:54","guid":{"rendered":"https:\/\/holaamericanews.com\/?p=28906"},"modified":"2025-02-12T20:32:57","modified_gmt":"2025-02-13T02:32:57","slug":"sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music","status":"publish","type":"post","link":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/","title":{"rendered":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense"},"content":{"rendered":"<div id=\"holaa-2410152061\" class=\"holaa-before-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-300x37.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-696x86.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><p><b>Por Christina Fern\u00e1ndez-Morrow, Hola Iowa<\/b><\/p>\n<p><span style=\"font-weight: 400;\"><strong>Des Moines, IA-<\/strong>La cantante, compositora y guitarrista Sonia De Los Santos sube al escenario del Des Moines Civic Center el 22 de febrero. Ha tocado para el p\u00fablico del Carnegie Hall, el Lincoln Center y Lollapalooza, y ahora trae al Heartland su sonido nominado a los Grammy. \u201cEstoy emocionada por FIESTA con Sonia De Los Santos. Mi banda y yo tocamos canciones en espa\u00f1ol e ingl\u00e9s para familias, ni\u00f1os, todas las edades y generaciones\u201d, dice entusiasmada.\u00a0<\/span><\/p><div id=\"holaa-4121884602\" class=\"holaa-ad-inside-articles-2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.aap.org\/en\/patient-care\/lead-exposure\/lead-exposure-in-children\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Web Ad July #1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg 2560w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-300x75.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1024x256.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-768x192.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1536x384.jpg 1536w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-2048x512.jpg 2048w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-696x174.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1068x267.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1920x480.jpg 1920w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" width=\"600\" height=\"640\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">Lo que hace que esta actuaci\u00f3n sea \u00fanica es que es la primera vez que colaborar\u00e1 con una banda de Iowa, Los Llaneros, para dar al espect\u00e1culo un toque local. Los Llaneros son conocidos por interpretar m\u00fasica de los llanos colombianos y venezolanos, considerada m\u00fasica \u201cvaquera\u201d, pero tambi\u00e9n tocan m\u00fasica de otras zonas de las dos naciones. Esta fusi\u00f3n \u00fanica promete un espect\u00e1culo interactivo en el que se invitar\u00e1 al p\u00fablico a cantar, bailar e interactuar con los int\u00e9rpretes. El espect\u00e1culo ser\u00e1 un viaje global a trav\u00e9s de la m\u00fasica mientras interpretan canciones inspiradas en la m\u00fasica folcl\u00f3rica mexicana, diversos ritmos latinoamericanos como el huapango, la cumbia, la salsa y el festejo, y tradiciones folcl\u00f3ricas estadounidenses.\u00a0<\/span><\/p>\n<figure id=\"attachment_28913\" aria-describedby=\"caption-attachment-28913\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/holaamericanews.com\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/sonia-de-los-santos-2\/\" rel=\"attachment wp-att-28913\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-28913\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-2.jpg\" alt=\"\" width=\"1200\" height=\"800\" srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-2.jpg 1200w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-2-300x200.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-2-1024x683.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-2-768x512.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-2-696x464.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-2-1068x712.jpg 1068w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-28913\" class=\"wp-caption-text\">Sonia De Los Santos<\/figcaption><\/figure>\n<p><span style=\"font-weight: 400;\">El arpista de Los Llaneros Daniel Rojas (colombiano), conocido cari\u00f1osamente en todo Iowa como \u201cDany Harp\u201d, la cuatrista y cantante Karin Stein (colombiana) y el maraquero, cantante y percusionista Edgar East (paname\u00f1o) se unir\u00e1n a ella como tr\u00edo utilizando instrumentos latinoamericanos para crear una actuaci\u00f3n \u00fanica en su g\u00e9nero exclusivamente para el p\u00fablico de Iowa.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De Los Santos, que presentar\u00e1 un espect\u00e1culo especial s\u00f3lo para estudiantes el 21 de febrero, se familiariz\u00f3 con Iowa durante su residencia en Des Moines Performing Arts en 2021. El estado le caus\u00f3 una impresi\u00f3n positiva, y siempre ha querido volver. \u201cMe encant\u00f3 visitar las escuelas. No me imaginaba que habr\u00eda tantos ni\u00f1os hispanohablantes que reaccionaran tan bien a las canciones biling\u00fces. Me encant\u00f3 conocer el centro del pa\u00eds y a todas las familias que se conectaron con la m\u00fasica. Por eso me mor\u00eda de ganas de volver y montar un espect\u00e1culo completo\u201d, recuerda.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De Los Santos ha sido aclamada por Billboard como \u201cuna de las artistas latinas de m\u00fasica infantil que deber\u00edas conocer\u201d y \u201cMejor m\u00fasica infantil latina\u201d. Tiene tres \u00e1lbumes de m\u00fasica familiar: \u201cMi Viaje: De Nuevo Le\u00f3n a la Isla de Nueva York\u201d, \u201c\u00a1Alegr\u00eda!\u201d y \u201cEsperanza\u201d. En 2024 realiz\u00f3 una gira con \u201cM\u00fasica\u201d, un espect\u00e1culo en el que rindi\u00f3 homenaje a las compositoras que la inspiraron a ella y a sus compa\u00f1eras de banda para hacer m\u00fasica.<\/span><\/p><div id=\"holaa-817283439\" class=\"holaa-ad-inside-articles holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/actionnetwork.org\/forms\/sign-up-for-progress-iowas-high-five\/\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"H5 Spanish 300 x 250 Progress Iowa\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/H5-Spanish-300-x-250-Progress-Iowa.png\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">No se pierda su actuaci\u00f3n interactiva en el Des Moines Civic Center el 22 de febrero, un espect\u00e1culo animado perfecto para que disfruten juntos ni\u00f1os y adultos. Las entradas cuestan desde 10 d\u00f3lares y pueden adquirirse en <a href=\"https:\/\/www.desmoinesperformingarts.org.\/\">https:\/\/www.desmoinesperformingarts.org.<\/a><\/span><\/p>\n<div id=\"holaa-2900252501\" class=\"holaa-after-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Por Christina Fern\u00e1ndez-Morrow, Hola Iowa Des Moines, IA-La cantante, compositora y guitarrista Sonia De Los Santos sube al escenario del Des Moines Civic Center el 22 de febrero. Ha tocado [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":28907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2489,11,8323,1693],"tags":[225,8055,936],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hola Iowa\"\/>\n\t<meta name=\"google-site-verification\" content=\"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"{:en}Hola America News{:}{:es}Hola America News{:}\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense | Hola America News\" \/>\n\t\t<meta property=\"og:description\" content=\"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-cover.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-cover.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"782\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-02-13T02:30:54+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-02-13T02:32:57+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense | Hola America News\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-cover.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#article\",\"name\":\"Sonia De Los Santos regresa a Iowa con una fusi\\u00f3n de m\\u00fasica folk latinoamericana y estadounidense | Hola America News\",\"headline\":\"Sonia De Los Santos regresa a Iowa con una fusi\\u00f3n de m\\u00fasica folk latinoamericana y estadounidense\",\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Sonia-De-Los-Santos-cover.jpg\",\"width\":1200,\"height\":782,\"caption\":\"Sonia De Los Santos\"},\"datePublished\":\"2025-02-12T20:30:54-06:00\",\"dateModified\":\"2025-02-12T20:32:57-06:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#webpage\"},\"articleSection\":\"Entertainment, Hola Iowa, Life story, music, Hola Iowa, Life story, Music, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"position\":2,\"name\":\"Latest News\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"position\":3,\"name\":\"Hola Iowa\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#listItem\",\"name\":\"Sonia De Los Santos regresa a Iowa con una fusi\\u00f3n de m\\u00fasica folk latinoamericana y estadounidense\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#listItem\",\"position\":4,\"name\":\"Sonia De Los Santos regresa a Iowa con una fusi\\u00f3n de m\\u00fasica folk latinoamericana y estadounidense\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\",\"name\":\"Hola America News\",\"description\":\"The Midwest's Latino News Source\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"telephone\":\"+13097215693\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HolaAmerica-News-web-logo.png\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#organizationLogo\",\"width\":1000,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/holaamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/\",\"name\":\"Hola Iowa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Hola Iowa\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#webpage\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/\",\"name\":\"Sonia De Los Santos regresa a Iowa con una fusi\\u00f3n de m\\u00fasica folk latinoamericana y estadounidense | Hola America News\",\"description\":\"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Sonia-De-Los-Santos-cover.jpg\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#mainImage\",\"width\":1200,\"height\":782,\"caption\":\"Sonia De Los Santos\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\\\/#mainImage\"},\"datePublished\":\"2025-02-12T20:30:54-06:00\",\"dateModified\":\"2025-02-12T20:32:57-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"name\":\"{:en}Hola America News{:}{:es}Hola America News{:}\",\"description\":\"The Midwest's Latino News Source\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense | Hola America News","description":"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences","canonical_url":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#article","name":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense | Hola America News","headline":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense","author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-cover.jpg","width":1200,"height":782,"caption":"Sonia De Los Santos"},"datePublished":"2025-02-12T20:30:54-06:00","dateModified":"2025-02-12T20:32:57-06:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#webpage"},"isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#webpage"},"articleSection":"Entertainment, Hola Iowa, Life story, music, Hola Iowa, Life story, Music, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/holaamericanews.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","position":2,"name":"Latest News","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","position":3,"name":"Hola Iowa","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#listItem","name":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#listItem","position":4,"name":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense","previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"}}]},{"@type":"Organization","@id":"https:\/\/holaamericanews.com\/es\/#organization","name":"Hola America News","description":"The Midwest's Latino News Source","url":"https:\/\/holaamericanews.com\/es\/","telephone":"+13097215693","logo":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/03\/HolaAmerica-News-web-logo.png","@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#organizationLogo","width":1000,"height":800},"image":{"@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/holaamerica"]},{"@type":"Person","@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author","url":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/","name":"Hola Iowa","image":{"@type":"ImageObject","@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Hola Iowa"}},{"@type":"WebPage","@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#webpage","url":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/","name":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense | Hola America News","description":"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#breadcrumblist"},"author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"creator":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-cover.jpg","@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#mainImage","width":1200,"height":782,"caption":"Sonia De Los Santos"},"primaryImageOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/#mainImage"},"datePublished":"2025-02-12T20:30:54-06:00","dateModified":"2025-02-12T20:32:57-06:00"},{"@type":"WebSite","@id":"https:\/\/holaamericanews.com\/es\/#website","url":"https:\/\/holaamericanews.com\/es\/","name":"{:en}Hola America News{:}{:es}Hola America News{:}","description":"The Midwest's Latino News Source","inLanguage":"es-ES","publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"{:en}Hola America News{:}{:es}Hola America News{:}","og:type":"article","og:title":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense | Hola America News","og:description":"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences","og:url":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/","og:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-cover.jpg","og:image:secure_url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-cover.jpg","og:image:width":1200,"og:image:height":782,"article:published_time":"2025-02-13T02:30:54+00:00","article:modified_time":"2025-02-13T02:32:57+00:00","article:publisher":"https:\/\/www.facebook.com\/HolaAmericaNews","twitter:card":"summary","twitter:site":"@HolaAmericaNews","twitter:title":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense | Hola America News","twitter:description":"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences","twitter:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2025\/02\/Sonia-De-Los-Santos-cover.jpg"},"aioseo_meta_data":{"post_id":"28906","title":null,"description":"Singer, songwriter, and guitarist Sonia De Los Santos takes the stage at the Des Moines Civic Center on February 22. She has performed for audiences","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-02-13 02:05:06","updated":"2026-01-28 12:00:21","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/\" title=\"Latest News\">Latest News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/\" title=\"Hola Iowa\">Hola Iowa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/holaamericanews.com\/es"},{"label":"Latest News","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/"},{"label":"Hola Iowa","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/"},{"label":"Sonia De Los Santos regresa a Iowa con una fusi\u00f3n de m\u00fasica folk latinoamericana y estadounidense","link":"https:\/\/holaamericanews.com\/es\/sonia-de-los-santos-returns-to-iowa-with-a-fusion-of-latin-american-and-us-folk-music\/"}],"_links":{"self":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/28906"}],"collection":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/comments?post=28906"}],"version-history":[{"count":0,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/28906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media\/28907"}],"wp:attachment":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media?parent=28906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/categories?post=28906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/tags?post=28906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}