{"id":21906,"date":"2023-06-19T12:59:25","date_gmt":"2023-06-19T17:59:25","guid":{"rendered":"https:\/\/holaamericanews.com\/?p=21906"},"modified":"2023-06-19T12:59:45","modified_gmt":"2023-06-19T17:59:45","slug":"latinas-leadership-transformed-school-mental-health","status":"publish","type":"post","link":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/","title":{"rendered":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas"},"content":{"rendered":"<div id=\"holaa-1601444159\" class=\"holaa-before-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-300x37.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-696x86.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><p><b>By Christina Fern\u00e1ndez-Morrow, Hola Iowa<\/b><\/p>\n<p><b>Des Moines, IA &#8211; <\/b><span style=\"font-weight: 400;\"><a href=\"https:\/\/holaamericanews.com\/celebrating-lgbtq-diversity-gabby-guerra-ceron\/\">Gabby Guerra Cer\u00f3n<\/a> oy\u00f3 hablar por primera vez de la organizaci\u00f3n <a href=\"https:\/\/www.pleasepassthelove.org\/about\/our-story\/\">Please Pass the Love<\/a> cuando compart\u00eda oficina con ellos en su primer trabajo al salir de la universidad. Nunca imagin\u00f3 entonces que un d\u00eda ser\u00eda la primera latina en dirigir esa organizaci\u00f3n sin fines de lucro centrada en transformar la salud mental escolar.<\/span><\/p><div id=\"holaa-1708293972\" class=\"holaa-ad-inside-articles-2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.aap.org\/en\/patient-care\/lead-exposure\/lead-exposure-in-children\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Web Ad July #1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg 2560w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-300x75.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1024x256.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-768x192.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1536x384.jpg 1536w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-2048x512.jpg 2048w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-696x174.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1068x267.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1920x480.jpg 1920w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" width=\"600\" height=\"640\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">Guerra Cer\u00f3n naci\u00f3 en El Salvador y se traslad\u00f3 a Iowa de ni\u00f1a, donde asisti\u00f3 a las escuelas p\u00fablicas de Des Moines desde la escuela primaria hasta la preparatoria. Cuando era peque\u00f1a, Guerra Cer\u00f3n recuerda que sus padres le dec\u00edan: &#8220;Vas a ir a la universidad, por eso nos mudamos aqu\u00ed&#8221;, y eso era mucha presi\u00f3n. No fue hasta que un profesor le recomend\u00f3 el Proyecto Talento de Iowa que pens\u00f3 que la universidad pod\u00eda ser posible. El programa, ya desaparecido, comenzaba en s\u00e9ptimo grado y permit\u00eda a los estudiantes obtener una beca para ir a la Universidad de Iowa despu\u00e9s de la preparatoria. Guerra Cer\u00f3n fue una de las pocas estudiantes que complet\u00f3 el programa, pero tem\u00eda que su condici\u00f3n de indocumentada le impidiera obtener la beca. No obstante, recibi\u00f3 ayuda de los profesores y del personal para llenar la solicitud y la FAFSA (Solicitud Gratuita de Ayuda Estudiantil). &#8220;Me daba miedo compartir la informaci\u00f3n de mis padres, pero me animaron a seguir adelante, ya que ellos hab\u00edan estado pagando impuestos. Pero no sab\u00edamos lo que significar\u00eda poner su informaci\u00f3n en m\u00e1s formularios del gobierno&#8221;. Adem\u00e1s de lidiar con el estr\u00e9s de ser la primera de su familia en ir a la universidad, tambi\u00e9n sufr\u00eda ansiedad y depresi\u00f3n no tratadas.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seg\u00fan el Departamento de Salud y Servicios Humanos de EE.UU., 1 de cada 5 ni\u00f1os estadounidenses de entre 3 y 17 a\u00f1os tiene problemas de salud mental, pero s\u00f3lo un 20% de ellos recibe el tratamiento que necesita. Entre los latinos, el n\u00famero de ni\u00f1os que reciben tratamiento de salud mental es a\u00fan menor. Esto es lo que atrajo a Guerra Cer\u00f3n a Please Pass the Love, una organizaci\u00f3n sin fines de lucro dedicada a eliminar el estigma en torno a la salud mental y a generar recursos, programas y formaci\u00f3n profesional en salud mental para las escuelas de todo Estados Unidos.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Trabajando con j\u00f3venes, se dio cuenta de los problemas de salud mental a los que se enfrentaban, similares a los suyos propios, y quiso cambiar las cosas para los ni\u00f1os de hoy. Guerra Cer\u00f3n se dio cuenta de que, cuando recib\u00edan apoyo y orientaci\u00f3n, los j\u00f3venes tomaban la iniciativa y dirig\u00edan programas que les ayudaban. &#8220;Saben que est\u00e1n marcando la diferencia. Vuelven a casa y hablan con sus familias de lo que han aprendido&#8221;. En Please Pass the Love, le gustaban especialmente los talleres porque llegaban r\u00e1pidamente a muchos estudiantes y a menudo era la primera vez que alguien dedicaba tiempo a hablar de habilidades de superaci\u00f3n, recursos de salud mental y autocuidado de una forma informativa y no enjuiciadora. Los j\u00f3venes respondieron con entusiasmo a los mensajes y se interesaron por crear clubes Stomp Out Stigma en sus escuelas. Estos clubes dieron voz a los estudiantes sobre la salud mental en la escuela y crearon l\u00edderes. A los estudiantes les apasionaba identificar las necesidades de salud mental, desarrollar proyectos de acci\u00f3n y asesorar a Please Pass the Love en su programaci\u00f3n juvenil. &#8220;Su opini\u00f3n es fundamental porque la reciben todos los d\u00edas&#8221;, dice Guerra Cer\u00f3n. Aunque los clubes Stomp Out Stigma estaban dirigidos por estudiantes, necesitaban administradores o profesores que actuaran como asesores, que fueran defensores y permitieran a los j\u00f3venes liderar mientras aprend\u00edan, exploraban y cuestionaban el statu quo. &#8220;Mi sue\u00f1o es ver este club en todas las escuelas secundarias y preparatorias de Iowa&#8221;, dice con una sonrisa.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En noviembre de 2022, la directora ejecutiva fundadora de Please Pass the Love dimiti\u00f3 y recomend\u00f3 a Guerra Cer\u00f3n para ocupar su lugar. La junta directiva estuvo de acuerdo y Guerra Cer\u00f3n asumi\u00f3 el cargo. Contaba con experiencia previa en la gesti\u00f3n de organizaciones sin fines de lucro como subdirectora de Al \u00c9xito, donde comenz\u00f3 su carrera. &#8220;Lo que sea, lo hice&#8221;, dice de su primer trabajo, en el que trabaj\u00f3 con la junta directiva, gestion\u00f3 las finanzas, coordin\u00f3 eventos y desarroll\u00f3 programas, &#8220;Estoy muy agradecida por esa experiencia, por trabajar tan estrechamente con un director ejecutivo. As\u00ed es como desarroll\u00e9 mis habilidades tan r\u00e1pidamente&#8221;. Y lo que es m\u00e1s importante, Guerra Cer\u00f3n tiene coraz\u00f3n para defender a los dem\u00e1s, especialmente a las comunidades BIPOC, LGBTQIIA+ e inmigrantes. Eso es lo que gui\u00f3 sus tiempos de estudiante universitaria en la Universidad de Iowa.<\/span><\/p><div id=\"holaa-2280272845\" class=\"holaa-ad-inside-articles holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/actionnetwork.org\/forms\/sign-up-for-progress-iowas-high-five\/\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"H5 Spanish 300 x 250 Progress Iowa\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/H5-Spanish-300-x-250-Progress-Iowa.png\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21909\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-3-1.jpg\" alt=\"\" width=\"728\" height=\"740\" srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-3-1.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-3-1-295x300.jpg 295w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-3-1-696x707.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Siendo la primera de su familia en ir a la universidad, estar tan lejos fue dif\u00edcil. Guerra Cer\u00f3n se sent\u00eda a menudo sola y volv\u00eda a casa en coche todos los fines de semana. No tuvo mucho tiempo para hacer amigos o participar en clubes, casas de cultura y eventos; experiencias que desear\u00eda haber aprovechado cuando tuvo la oportunidad. A Guerra Cer\u00f3n le costaba disfrutar de las clases hasta que cambi\u00f3 la carrera de Administraci\u00f3n Empresarial por una personalizada para ella que la llev\u00f3 a obtener una licenciatura en \u00c9tica y Pol\u00edtica P\u00fablica, una especializaci\u00f3n en Estudios Latinos y un certificado en Gesti\u00f3n de Organizaciones sin Fines de Lucro. Una vez en ese camino, le encantaron sus cursos y empez\u00f3 a pensar en una carrera en el sector no lucrativo. Desgraciadamente, mientras estaba en la universidad no hab\u00eda creado una red que pudiera ayudarla a encontrar un empleo. Envi\u00f3 solicitudes a todas las organizaciones sin fines de lucro que conoc\u00eda y s\u00f3lo una respondi\u00f3 de inmediato. Mientras trabajaba en Al \u00c9xito vio a j\u00f3venes con problemas mentales, emocionales, de comportamiento o de desarrollo que afectaban negativamente a su capacidad para centrarse en la escuela y desarrollarse como j\u00f3venes adultos. La mayor\u00eda de los estudiantes latinos nunca hab\u00edan hablado con sus padres sobre lo que estaban experimentando y hab\u00edan interiorizado sentimientos negativos sobre s\u00ed mismos debido a sus problemas de salud mental no tratados. Estaba impresionada por el trabajo que Al \u00c9xito hab\u00eda realizado en el Informe sobre la salud mental de los j\u00f3venes latinos y quer\u00eda implicarse m\u00e1s en las soluciones para algunos de los problemas identificados. Cuando se enter\u00f3 de que el Director de Participaci\u00f3n Juvenil hab\u00eda dimitido de Please Pass the Love, Guerra Cer\u00f3n present\u00f3 su candidatura. No fue una elecci\u00f3n f\u00e1cil. &#8220;Como profesional joven y apasionada, fue una decisi\u00f3n dif\u00edcil. Hab\u00eda aprendido tanto y hab\u00eda conocido a tantos estudiantes incre\u00edbles en Al \u00c9xito que quer\u00eda seguir trabajando con ellos y verles triunfar. Dawn me hab\u00eda apoyado tanto y hab\u00eda confiado tanto en m\u00ed para dejarme probar tantas cosas, lo que hizo m\u00e1s dif\u00edcil marcharme, pero tambi\u00e9n sab\u00eda que deb\u00eda explorar otras oportunidades para crecer como profesional&#8221;, dice Guerra Cer\u00f3n.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A Guerra Cer\u00f3n le llev\u00f3 alg\u00fan tiempo adaptarse a trabajar con una poblaci\u00f3n de estudiantes tan diferente. &#8220;No era tanto una cuesti\u00f3n cultural como de estigma. Lo vi en mi vida. Yo luchaba contra la ansiedad, pero no ten\u00eda palabras para hablar de ello. No me diagnosticaron hasta los 23 a\u00f1os. Que no hablemos de salud mental en la comunidad latina no significa que no exista. Una vez que me sumerg\u00ed en este trabajo y tuve acceso a recursos de salud mental al tener seguro y m\u00e1s educaci\u00f3n al respecto, mi vida empez\u00f3 a cambiar&#8221;. Please Pass the Love ayud\u00f3 a normalizar el lenguaje en torno a lo que Guerra Cer\u00f3n hab\u00eda sentido toda su vida y le permiti\u00f3 ver c\u00f3mo otros miembros de su familia luchaban en silencio. La hizo estar m\u00e1s decidida que nunca a elevar las voces de los latinos y los j\u00f3venes y a difundir la ayuda que existe. &#8220;Tenemos que ir m\u00e1s all\u00e1 de las palabras. No tienes por qu\u00e9 sufrir solo; no has hecho nada malo. Est\u00e1 bien apoyarte en tu comunidad y en los recursos que existen&#8221;. Algunos de los servicios que recomienda con frecuencia son el asesoramiento individual gratuito para chicas j\u00f3venes en el Centro de Recursos para Mujeres J\u00f3venes; la terapia escolar, donde los terapeutas atienden a los ni\u00f1os en sus escuelas durante el d\u00eda; Orchard Place y Easter Seals, donde los psiquiatras hacen revisiones de salud mental y pueden hacer un diagn\u00f3stico formal. Guerra Cer\u00f3n fue la primera latina queer en dirigir Please Pass the Love hasta que la agencia se disolvi\u00f3 en 2023.<\/span><\/p><div id=\"holaa-1162258802\" class=\"holaa-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/300x250.jpg\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><br style=\"font-weight: 400;\" \/><br style=\"font-weight: 400;\" \/><\/p>\n<div id=\"holaa-469674063\" class=\"holaa-after-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>By Christina Fern\u00e1ndez-Morrow, Hola Iowa Des Moines, IA &#8211; Gabby Guerra Cer\u00f3n oy\u00f3 hablar por primera vez de la organizaci\u00f3n Please Pass the Love cuando compart\u00eda oficina con ellos en [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":21910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[27,408,1874,14,2323],"tags":[225,2248,2190,3002,7389],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Gabby Guerra Cer\u00f3n never imagined she would one day be the first Latina to run &#039;Please Pass the Love&#039; that focused on transforming school mental health.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hola Iowa\"\/>\n\t<meta name=\"google-site-verification\" content=\"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"{:en}Hola America News{:}{:es}Hola America News{:}\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas\" \/>\n\t\t<meta property=\"og:description\" content=\"Gabby Guerra Cer\u00f3n never imagined she would one day be the first Latina to run &#039;Please Pass the Love&#039; that focused on transforming school mental health.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-1-scaled-e1687195348758.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-1-scaled-e1687195348758.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-19T17:59:25+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-19T17:59:45+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Gabby Guerra Cer\u00f3n never imagined she would one day be the first Latina to run &#039;Please Pass the Love&#039; that focused on transforming school mental health.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-1-scaled-e1687195348758.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#article\",\"name\":\"El liderazgo de una latina transform\\u00f3 el acceso a la salud mental en las escuelas\",\"headline\":\"El liderazgo de una latina transform\\u00f3 el acceso a la salud mental en las escuelas\",\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Gabby-1-scaled-e1687195348758.jpg\",\"width\":1200,\"height\":675},\"datePublished\":\"2023-06-19T12:59:25-05:00\",\"dateModified\":\"2023-06-19T12:59:45-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#webpage\"},\"articleSection\":\"Business, Culture, Entrepreneurs, Health, Latino Owned Business, Hola Iowa, Latina Owned Business, Mental Health, nonprofit, Please Pass the Love, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"position\":2,\"name\":\"Latest News\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/health\\\/#listItem\",\"name\":\"Health\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/health\\\/#listItem\",\"position\":3,\"name\":\"Health\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/health\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#listItem\",\"name\":\"El liderazgo de una latina transform\\u00f3 el acceso a la salud mental en las escuelas\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#listItem\",\"position\":4,\"name\":\"El liderazgo de una latina transform\\u00f3 el acceso a la salud mental en las escuelas\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/health\\\/#listItem\",\"name\":\"Health\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\",\"name\":\"Hola America News\",\"description\":\"The Midwest's Latino News Source\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"telephone\":\"+13097215693\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HolaAmerica-News-web-logo.png\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#organizationLogo\",\"width\":1000,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/holaamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/\",\"name\":\"Hola Iowa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Hola Iowa\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#webpage\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/\",\"name\":\"El liderazgo de una latina transform\\u00f3 el acceso a la salud mental en las escuelas\",\"description\":\"Gabby Guerra Cer\\u00f3n never imagined she would one day be the first Latina to run 'Please Pass the Love' that focused on transforming school mental health.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Gabby-1-scaled-e1687195348758.jpg\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#mainImage\",\"width\":1200,\"height\":675},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/latinas-leadership-transformed-school-mental-health\\\/#mainImage\"},\"datePublished\":\"2023-06-19T12:59:25-05:00\",\"dateModified\":\"2023-06-19T12:59:45-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"name\":\"{:en}Hola America News{:}{:es}Hola America News{:}\",\"description\":\"The Midwest's Latino News Source\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas","description":"Gabby Guerra Cer\u00f3n never imagined she would one day be the first Latina to run 'Please Pass the Love' that focused on transforming school mental health.","canonical_url":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#article","name":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas","headline":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas","author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-1-scaled-e1687195348758.jpg","width":1200,"height":675},"datePublished":"2023-06-19T12:59:25-05:00","dateModified":"2023-06-19T12:59:45-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#webpage"},"isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#webpage"},"articleSection":"Business, Culture, Entrepreneurs, Health, Latino Owned Business, Hola Iowa, Latina Owned Business, Mental Health, nonprofit, Please Pass the Love, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/holaamericanews.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","position":2,"name":"Latest News","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/health\/#listItem","name":"Health"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/health\/#listItem","position":3,"name":"Health","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/health\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#listItem","name":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#listItem","position":4,"name":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas","previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/health\/#listItem","name":"Health"}}]},{"@type":"Organization","@id":"https:\/\/holaamericanews.com\/es\/#organization","name":"Hola America News","description":"The Midwest's Latino News Source","url":"https:\/\/holaamericanews.com\/es\/","telephone":"+13097215693","logo":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/03\/HolaAmerica-News-web-logo.png","@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#organizationLogo","width":1000,"height":800},"image":{"@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/holaamerica"]},{"@type":"Person","@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author","url":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/","name":"Hola Iowa","image":{"@type":"ImageObject","@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Hola Iowa"}},{"@type":"WebPage","@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#webpage","url":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/","name":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas","description":"Gabby Guerra Cer\u00f3n never imagined she would one day be the first Latina to run 'Please Pass the Love' that focused on transforming school mental health.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#breadcrumblist"},"author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"creator":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-1-scaled-e1687195348758.jpg","@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#mainImage","width":1200,"height":675},"primaryImageOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/#mainImage"},"datePublished":"2023-06-19T12:59:25-05:00","dateModified":"2023-06-19T12:59:45-05:00"},{"@type":"WebSite","@id":"https:\/\/holaamericanews.com\/es\/#website","url":"https:\/\/holaamericanews.com\/es\/","name":"{:en}Hola America News{:}{:es}Hola America News{:}","description":"The Midwest's Latino News Source","inLanguage":"es-ES","publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"{:en}Hola America News{:}{:es}Hola America News{:}","og:type":"article","og:title":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas","og:description":"Gabby Guerra Cer\u00f3n never imagined she would one day be the first Latina to run 'Please Pass the Love' that focused on transforming school mental health.","og:url":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/","og:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-1-scaled-e1687195348758.jpg","og:image:secure_url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-1-scaled-e1687195348758.jpg","og:image:width":1200,"og:image:height":675,"article:published_time":"2023-06-19T17:59:25+00:00","article:modified_time":"2023-06-19T17:59:45+00:00","article:publisher":"https:\/\/www.facebook.com\/HolaAmericaNews","twitter:card":"summary","twitter:site":"@HolaAmericaNews","twitter:title":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas","twitter:description":"Gabby Guerra Cer\u00f3n never imagined she would one day be the first Latina to run 'Please Pass the Love' that focused on transforming school mental health.","twitter:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Gabby-1-scaled-e1687195348758.jpg"},"aioseo_meta_data":{"post_id":"21906","title":"#post_title","description":"Gabby Guerra Cer\u00f3n never imagined she would one day be the first Latina to run 'Please Pass the Love' that focused on transforming school mental health.","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-19 17:14:56","updated":"2026-01-28 10:52:21","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/\" title=\"Latest News\">Latest News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/health\/\" title=\"Health\">Health<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/holaamericanews.com\/es"},{"label":"Latest News","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/"},{"label":"Health","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/health\/"},{"label":"El liderazgo de una latina transform\u00f3 el acceso a la salud mental en las escuelas","link":"https:\/\/holaamericanews.com\/es\/latinas-leadership-transformed-school-mental-health\/"}],"_links":{"self":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/21906"}],"collection":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/comments?post=21906"}],"version-history":[{"count":0,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/21906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media\/21910"}],"wp:attachment":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media?parent=21906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/categories?post=21906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/tags?post=21906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}