{"id":21896,"date":"2023-06-19T12:49:16","date_gmt":"2023-06-19T17:49:16","guid":{"rendered":"https:\/\/holaamericanews.com\/?p=21896"},"modified":"2023-06-20T08:10:14","modified_gmt":"2023-06-20T13:10:14","slug":"small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns","status":"publish","type":"post","link":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/","title":{"rendered":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales"},"content":{"rendered":"<div id=\"holaa-873101981\" class=\"holaa-before-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-300x37.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-696x86.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><p><strong>Por Rafael Colon, Vice President, Small Business Banker, Bank of America, Iowa\u00a0\u00a0<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">A pesar de las adversidades en la econom\u00eda, los propietarios de peque\u00f1as empresas de Iowa conf\u00edan en su capacidad para administrar sus negocios en tiempos dif\u00edciles. Especialmente dado que las <\/span><a href=\"https:\/\/advocacy.sba.gov\/wp-content\/uploads\/2022\/08\/Small-Business-Economic-Profile-IA.pdf\"><span style=\"font-weight: 400;\">peque\u00f1as empresas representan el 99.3% de las empresas de Iowa<\/span><\/a><span style=\"font-weight: 400;\">, tener acceso a los recursos ayuda a los propietarios de preque\u00f1as empresas a sentirese seguros e incluso puede alentarlos a expandirse.\u00a0\u00a0<\/span><\/p><div id=\"holaa-2796256082\" class=\"holaa-ad-inside-articles-2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.aap.org\/en\/patient-care\/lead-exposure\/lead-exposure-in-children\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Web Ad July #1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg 2560w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-300x75.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1024x256.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-768x192.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1536x384.jpg 1536w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-2048x512.jpg 2048w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-696x174.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1068x267.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1920x480.jpg 1920w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" width=\"600\" height=\"640\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><span style=\"font-weight: 400;\">Seg\u00fan un nuevo <\/span><a href=\"https:\/\/about.bankofamerica.com\/content\/dam\/about\/report-center\/sbor\/2023\/2023-small-business-owner-report.pdf\"><span style=\"font-weight: 400;\">estudio de Bank of America<\/span><\/a><span style=\"font-weight: 400;\">, los due\u00f1os de negocios se sienten presionados por la inflaci\u00f3n y los problemas de la cadena de suministro, pero la mayor\u00eda de los encuestados (76%) se siente bien posicionada para tener un a\u00f1o s\u00f3lido\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Como inmigrante de Guinea, \u00c1frica, Love Adjei, empresaria de bienes ra\u00edces de un complejo de cuatro y tres complejos, as\u00ed como directora ejecutiva del servicio de lavander\u00eda llamado Lapa Laundry en Des Moines, est\u00e1 lista para aumentar las apuestas comerciales a trav\u00e9s de sus muchos esfuerzos y utiliza sus recursos en Bank of America para hacerlo.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los empresarios est\u00e1n monitoreando algunas situaciones que presentan un reto para sus planes de negocios en 2023, y afirman que su principal preocupaci\u00f3n se centra en la inflaci\u00f3n, los precios de las materias primas y una posible recesi\u00f3n. Sin embargo, m\u00e1s de la mitad de los due\u00f1os de negocios (56%) report\u00f3 mayores ingresos en 2022 que en 2021, y la mayor\u00eda (65%) espera que sus ingresos aumenten en los pr\u00f3ximos 12 meses. Adem\u00e1s, el 82% de los empresarios dice que desea obtener financiamiento para su negocio el pr\u00f3ximo a\u00f1o, en comparaci\u00f3n con el 70% de la primavera pasada, y el 34% de los due\u00f1os de negocios planea contratar personal este a\u00f1o, en comparaci\u00f3n con el 26% de la primavera pasada.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-21903\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Iowa-Small-Businesses-Profile-1024x650.jpg\" alt=\"\" width=\"696\" height=\"442\" srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Iowa-Small-Businesses-Profile-1024x650.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Iowa-Small-Businesses-Profile-300x190.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Iowa-Small-Businesses-Profile-768x487.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Iowa-Small-Businesses-Profile-696x442.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Iowa-Small-Businesses-Profile-1068x678.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Iowa-Small-Businesses-Profile.jpg 1097w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Entonces, \u00bfqu\u00e9 deben tener en cuenta los empresarios para 2023? Estas son tres de las principales ideas, tendencias y obst\u00e1culos que las empresas deben tener en cuenta al prepararse para enfrentar este a\u00f1o:\u00a0<\/span><\/p><div id=\"holaa-4003009197\" class=\"holaa-ad-inside-articles holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/actionnetwork.org\/forms\/sign-up-for-progress-iowas-high-five\/\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"H5 Spanish 300 x 250 Progress Iowa\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/H5-Spanish-300-x-250-Progress-Iowa.png\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p><b>\u00a0<\/b><\/p>\n<h2><b>Preocupaciones y retos laborales\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">El cincuenta y dos por ciento de los due\u00f1os de negocios dice que la escasez de mano de obra est\u00e1 afectando su negocio y, como resultado, muchos empresarios est\u00e1n trabajando m\u00e1s horas, tienen problemas para ocupar las vacantes y est\u00e1n modificando sus horas de operaci\u00f3n. El veintiuno por ciento de los due\u00f1os de negocios tambi\u00e9n report\u00f3 p\u00e9rdidas de clientes debido a problemas laborales.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para hacer frente a estos retos, los due\u00f1os de negocios est\u00e1n adoptando nuevas estrategias para retener y atraer talento. En los \u00faltimos 12 meses, el 51% de los propietarios de empresas implement\u00f3 ventajas y beneficios adicionales, incluido un salario base m\u00e1s alto para los nuevos empleados, lo que permiti\u00f3 el trabajo remoto o h\u00edbrido, la introducci\u00f3n de nuevas opciones de capacitaci\u00f3n para los empleados y la prestaci\u00f3n de beneficios de atenci\u00f3n m\u00e9dica adicionales.\u00a0<\/span><\/p><div id=\"holaa-3481760491\" class=\"holaa-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/300x250.jpg\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><span style=\"font-weight: 400;\">Los empresarios que ya implementaron esos cambios est\u00e1n viendo los frutos de su esfuerzo: el 75% de los due\u00f1os de negocios report\u00f3 que proporcionar beneficios adicionales para retener el talento durante los \u00faltimos 12 meses tuvo un gran impacto en la moral y la retenci\u00f3n de los empleados.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<h2><b>Nuevas oportunidades de crecimiento\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Los empresarios deber\u00e1n ser creativos para hacer crecer sus negocios durante el pr\u00f3ximo a\u00f1o y podr\u00eda serles \u00fatil aprovechar lo \u00faltimo en herramientas y recursos digitales.\u00a0<\/span><\/p><div id=\"holaa-1965821790\" class=\"holaa-content_2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p><span style=\"font-weight: 400;\">El ochenta por ciento de los due\u00f1os de negocios optimiz\u00f3 digitalmente sus negocios el a\u00f1o pasado mediante la adopci\u00f3n de nuevas herramientas y tecnolog\u00edas, y el 49% de los due\u00f1os de negocios planea incorporar herramientas de automatizaci\u00f3n e inteligencia artificial (IA) en 2023. En general, el 90% de los propietarios de peque\u00f1as empresas dice que el uso de herramientas digitales le ayud\u00f3 a hacer m\u00e1s eficientes sus operaciones comerciales.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La mayor\u00eda de los due\u00f1os de negocios est\u00e1 utilizando nuevas tecnolog\u00edas para aceptar m\u00e1s formas de pagos sin dinero en efectivo y agilizar la n\u00f3mina y la contabilidad, pero las herramientas digitales tambi\u00e9n pueden ayudar a facilitar el marketing: casi la mitad de los due\u00f1os de negocios emplea principalmente una estrategia de marketing digital o en l\u00ednea. Los empresarios tambi\u00e9n est\u00e1n utilizando herramientas digitales para ayudarles a mantenerse organizados, llegar a nuevos clientes e implementar t\u00e1cticas comerciales sostenibles.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00a0<\/span><\/p>\n<h2><b>Marcar la pauta\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Los \u00faltimos tres a\u00f1os han obligado a los empresarios a adoptar una mentalidad \u00e1gil en su intento de mantenerse un paso adelante. Los empresarios que buscan expandir sus operaciones comerciales en el transcurso de 2023 deben considerar implementar los siguientes principios de un modelo comercial adaptable:\u00a0<\/span><\/p>\n<ol>\n<li style=\"font-weight: 400;\"><b>Tener flexibilidad<\/b><span style=\"font-weight: 400;\">: los due\u00f1os de negocios de hoy en d\u00eda son igualmente creativos, optimistas, pr\u00e1cticos y activos con respecto a los objetivos comerciales que establecen y hacia d\u00f3nde se dirige su negocio. Los due\u00f1os de negocios deben revisar sus planes y permanecer abiertos a modificar su direcci\u00f3n a medida que avanza el a\u00f1o.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Ser objetivos<\/b><span style=\"font-weight: 400;\">: al establecer metas espec\u00edficas y mensurables, los due\u00f1os de negocios podr\u00e1n determinar la efectividad de sus estrategias e identificar en qu\u00e9 \u00e1reas podr\u00edan mejorar sus planes. Establecer objetivos puede ayudarles a medir el \u00e9xito actual y futuro de su modelo de negocio.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\"><b>Estar dispuestos a aprender<\/b><span style=\"font-weight: 400;\">: los empresarios que se comprometan a aprender nuevas habilidades podr\u00e1n adaptarse mejor a los nuevos retos. Al conectarse con otros empresarios y socios, los empresarios pueden obtener <a href=\"https:\/\/holaamericanews.com\/mercado-us-bank-offer-small-business-workshops\/\">valiosos mentores<\/a> y conocimientos sobre c\u00f3mo hacer crecer y mejorar su negocio.<\/span><b>\u00a0<\/b><\/li>\n<\/ol>\n<p><span style=\"font-weight: 400;\">Ya sea que una peque\u00f1a empresa haya existido durante d\u00e9cadas o reci\u00e9n est\u00e9 abriendo sus puertas, ser parte de una organizaci\u00f3n como Bank of America, que se compromete a proporcionar los recursos necesarios para operar y hacer crecer una empresa en cada etapa, marca la diferencia.<\/span><\/p>\n<p><em><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-21953\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Picture1.jpg\" alt=\"\" width=\"104\" height=\"125\" \/><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Rafael Colon, Vice President, Small Business Banker, Bank of America, Iowa\u00a0<\/em><\/p>\n<div id=\"holaa-832383174\" class=\"holaa-after-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Por Rafael Colon, Vice President, Small Business Banker, Bank of America, Iowa\u00a0\u00a0 A pesar de las adversidades en la econom\u00eda, los propietarios de peque\u00f1as empresas de Iowa conf\u00edan en su [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":21902,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[27,1874],"tags":[7391,855,225],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hola Iowa\"\/>\n\t<meta name=\"google-site-verification\" content=\"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"{:en}Hola America News{:}{:es}Hola America News{:}\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales | Hola America News\" \/>\n\t\t<meta property=\"og:description\" content=\"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Small-Business.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Small-Business.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1129\" \/>\n\t\t<meta property=\"og:image:height\" content=\"703\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2023-06-19T17:49:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-06-20T13:10:14+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales | Hola America News\" \/>\n\t\t<meta name=\"twitter:description\" content=\"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Small-Business.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#article\",\"name\":\"Las peque\\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\\u00f3micas y laborales | Hola America News\",\"headline\":\"Las peque\\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\\u00f3micas y laborales\",\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Small-Business.jpg\",\"width\":1129,\"height\":703},\"datePublished\":\"2023-06-19T12:49:16-05:00\",\"dateModified\":\"2023-06-20T08:10:14-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#webpage\"},\"articleSection\":\"Business, Entrepreneurs, Bank of America, Business, Hola Iowa, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"position\":2,\"name\":\"Latest News\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/business\\\/#listItem\",\"name\":\"Business\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/business\\\/#listItem\",\"position\":3,\"name\":\"Business\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/business\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#listItem\",\"name\":\"Las peque\\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\\u00f3micas y laborales\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#listItem\",\"position\":4,\"name\":\"Las peque\\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\\u00f3micas y laborales\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/business\\\/#listItem\",\"name\":\"Business\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\",\"name\":\"Hola America News\",\"description\":\"The Midwest's Latino News Source\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"telephone\":\"+13097215693\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HolaAmerica-News-web-logo.png\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#organizationLogo\",\"width\":1000,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/holaamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/\",\"name\":\"Hola Iowa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Hola Iowa\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#webpage\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/\",\"name\":\"Las peque\\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\\u00f3micas y laborales | Hola America News\",\"description\":\"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Small-Business.jpg\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#mainImage\",\"width\":1129,\"height\":703},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\\\/#mainImage\"},\"datePublished\":\"2023-06-19T12:49:16-05:00\",\"dateModified\":\"2023-06-20T08:10:14-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"name\":\"{:en}Hola America News{:}{:es}Hola America News{:}\",\"description\":\"The Midwest's Latino News Source\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales | Hola America News","description":"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.","canonical_url":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#article","name":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales | Hola America News","headline":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales","author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Small-Business.jpg","width":1129,"height":703},"datePublished":"2023-06-19T12:49:16-05:00","dateModified":"2023-06-20T08:10:14-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#webpage"},"isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#webpage"},"articleSection":"Business, Entrepreneurs, Bank of America, Business, Hola Iowa, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/holaamericanews.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","position":2,"name":"Latest News","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/business\/#listItem","name":"Business"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/business\/#listItem","position":3,"name":"Business","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/business\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#listItem","name":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#listItem","position":4,"name":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales","previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/business\/#listItem","name":"Business"}}]},{"@type":"Organization","@id":"https:\/\/holaamericanews.com\/es\/#organization","name":"Hola America News","description":"The Midwest's Latino News Source","url":"https:\/\/holaamericanews.com\/es\/","telephone":"+13097215693","logo":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/03\/HolaAmerica-News-web-logo.png","@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#organizationLogo","width":1000,"height":800},"image":{"@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/holaamerica"]},{"@type":"Person","@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author","url":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/","name":"Hola Iowa","image":{"@type":"ImageObject","@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Hola Iowa"}},{"@type":"WebPage","@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#webpage","url":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/","name":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales | Hola America News","description":"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#breadcrumblist"},"author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"creator":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Small-Business.jpg","@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#mainImage","width":1129,"height":703},"primaryImageOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/#mainImage"},"datePublished":"2023-06-19T12:49:16-05:00","dateModified":"2023-06-20T08:10:14-05:00"},{"@type":"WebSite","@id":"https:\/\/holaamericanews.com\/es\/#website","url":"https:\/\/holaamericanews.com\/es\/","name":"{:en}Hola America News{:}{:es}Hola America News{:}","description":"The Midwest's Latino News Source","inLanguage":"es-ES","publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"{:en}Hola America News{:}{:es}Hola America News{:}","og:type":"article","og:title":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales | Hola America News","og:description":"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.","og:url":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/","og:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Small-Business.jpg","og:image:secure_url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Small-Business.jpg","og:image:width":1129,"og:image:height":703,"article:published_time":"2023-06-19T17:49:16+00:00","article:modified_time":"2023-06-20T13:10:14+00:00","article:publisher":"https:\/\/www.facebook.com\/HolaAmericaNews","twitter:card":"summary","twitter:site":"@HolaAmericaNews","twitter:title":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales | Hola America News","twitter:description":"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.","twitter:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/06\/Small-Business.jpg"},"aioseo_meta_data":{"post_id":"21896","title":"#custom_field","description":"What do small business owners need to keep in mind for 2023? Here are three of the most significant insights, trends, and obstacles they should be prepared for.","keywords":[],"keyphrases":{"focus":{"keyphrase":null,"score":68,"analysis":{"keyphraseInTitle":{"score":3,"maxScore":9,"error":1},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":1,"maxScore":5,"error":1},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":{"score":3,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":0,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-06-19 16:48:06","updated":"2026-01-28 10:52:21","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/\" title=\"Latest News\">Latest News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/business\/\" title=\"Business\">Business<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLas peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/holaamericanews.com\/es"},{"label":"Latest News","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/"},{"label":"Business","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/business\/"},{"label":"Las peque\u00f1as empresas siguen siendo optimistas en el 2023 a pesar de las preocupaciones econ\u00f3micas y laborales","link":"https:\/\/holaamericanews.com\/es\/small-businesses-remain-bullish-for-2023-despite-economic-and-labor-concerns\/"}],"_links":{"self":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/21896"}],"collection":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/comments?post=21896"}],"version-history":[{"count":0,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/21896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media\/21902"}],"wp:attachment":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media?parent=21896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/categories?post=21896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/tags?post=21896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}