{"id":19399,"date":"2022-07-14T15:08:24","date_gmt":"2022-07-14T20:08:24","guid":{"rendered":"https:\/\/holaamericanews.com\/?p=19399"},"modified":"2022-07-15T12:41:35","modified_gmt":"2022-07-15T17:41:35","slug":"lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members","status":"publish","type":"post","link":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/","title":{"rendered":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva"},"content":{"rendered":"<div id=\"holaa-1904949495\" class=\"holaa-before-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"728&#215;90\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90.jpg 728w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-300x37.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/728x90-696x86.jpg 696w\" sizes=\"(max-width: 728px) 100vw, 728px\" width=\"728\" height=\"90\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/><p><strong>Por Clark Kauffman, Iowa Capital Dispatch<\/strong><\/p>\n<p>Un hombre de Cedar Rapids est\u00e1 demandando a la ciudad y al alcalde por una disposici\u00f3n que exige que cinco miembros de la Junta de Revisi\u00f3n Ciudadana del departamento de polic\u00eda sean personas de color.<\/p><div id=\"holaa-1480168653\" class=\"holaa-ad-inside-articles-2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.aap.org\/en\/patient-care\/lead-exposure\/lead-exposure-in-children\/\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"Web Ad July #1\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-scaled.jpg 2560w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-300x75.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1024x256.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-768x192.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1536x384.jpg 1536w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-2048x512.jpg 2048w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-696x174.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1068x267.jpg 1068w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Web-Ad-July-1-1920x480.jpg 1920w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" width=\"600\" height=\"640\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p>Kevin Wymore, un analista de salud p\u00fablica jubilado, alega que en febrero de 2021, la ciudad de Cedar Rapids adopt\u00f3 una disposici\u00f3n por la que se establec\u00eda una Junta de Revisi\u00f3n Ciudadana independiente de nueve miembros, cada uno de los cuales era designado por el alcalde con mandatos escalonados de tres a\u00f1os.<\/p>\n<p>La junta se encarga de revisar los informes trimestrales del jefe de polic\u00eda que incluyen datos raciales y \u00e9tnicos relacionados con las paradas de tr\u00e1fico de los agentes de polic\u00eda y las quejas de los ciudadanos sobre los agentes de polic\u00eda.<\/p>\n<p>La normativa exige que la junta &#8220;incluya un m\u00ednimo de cinco miembros con derecho a voto que se identifiquen como personas de color&#8221;. Adem\u00e1s, tres miembros con derecho a voto se seleccionar\u00e1n de entre las solicitudes presentadas por personas que trabajen en organizaciones sin fines de lucro centradas en la defensa y la justicia racial para los ciudadanos poco representados de Cedar Rapids.<\/p>\n<p>Wymore, que es de raza blanca, solicit\u00f3 un puesto en la junta cuando sus miembros fueron seleccionados originalmente en mayo de 2021. Tiene un m\u00e1ster en pol\u00edtica p\u00fablica y, en su demanda, dice que es profesor voluntario de ingl\u00e9s para adultos reci\u00e9n llegados a Estados Unidos desde \u00c1frica Occidental.<\/p><div id=\"holaa-2118581125\" class=\"holaa-ad-inside-articles holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/actionnetwork.org\/forms\/sign-up-for-progress-iowas-high-five\/\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"H5 Spanish 300 x 250 Progress Iowa\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/H5-Spanish-300-x-250-Progress-Iowa.png\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div><br style=\"clear: both; display: block; float: none;\"\/>\n<p>No se le permiti\u00f3 formar parte de la junta, y alega que posteriormente pregunt\u00f3 a Brad Hart, entonces alcalde, por qu\u00e9 no hab\u00eda sido elegido. La demanda alega que Hart indic\u00f3 que &#8220;s\u00f3lo hab\u00eda unos pocos puestos para el p\u00fablico en general&#8221; en la junta, sugiriendo que, como individuo blanco, Wymore no fue considerado para los cinco puestos de la junta reservados para personas de color.<\/p>\n<p>En enero de 2022, Wymore solicit\u00f3 una de las dos vacantes de la junta que, seg\u00fan \u00e9l, fueron causadas por la &#8220;persistente inasistencia&#8221; de algunos de sus miembros. Wymore fue rechazado por segunda vez. La demanda alega que un funcionario de la ciudad le inform\u00f3 m\u00e1s tarde por correo electr\u00f3nico que no fue considerado por la alcaldesa Tiffany O&#8217;Donnell porque no ten\u00eda experiencia trabajando o siendo voluntario en una organizaci\u00f3n para las poblaciones desatendidas de la ciudad.<\/p><div id=\"holaa-983846553\" class=\"holaa-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.desmoinesperformingarts.org\/whats-on\/events\/2025-26\/broadway\/wicked?utm_source=HolaIowa&#038;utm_medium=DigitalAds&#038;utm_campaign=July26\" rel=\"noopener\" class=\"a2t-link\" target=\"_blank\" aria-label=\"300&#215;250\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/300x250.jpg\" alt=\"\"  width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>La demanda de Wymore, presentada en un tribunal federal, sostiene que la disposici\u00f3n de la ciudad viola la garant\u00eda de igualdad de protecci\u00f3n de la Constituci\u00f3n de los Estados Unidos.<\/p>\n<p>&#8220;No hay ninguna diferencia legal en que la discriminaci\u00f3n racial impuesta por la ciudad de Cedar Rapids pueda alegarse como benigna o motivada por &#8216;buenas&#8217; razones&#8221;, afirma la demanda. &#8220;En virtud de la ordenanza, las personas que no se identifican como personas de color est\u00e1n categ\u00f3ricamente excluidas de la consideraci\u00f3n para cinco de los nueve puestos de la junta&#8221;.<\/p><div id=\"holaa-1660335925\" class=\"holaa-content_2 holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>\n<p>La demanda busca una declaraci\u00f3n judicial de que la ordenanza viola la Constituci\u00f3n de los Estados Unidos, as\u00ed como una orden que exija a la ciudad la disoluci\u00f3n de la junta y la reconstituci\u00f3n de sus miembros sin tener en cuenta la raza.<\/p>\n<p>El abogado de Wymore es Alan R. Ostergren, antiguo fiscal del condado de Muscatine que ahora dirige el Instituto Kirkwood, una organizaci\u00f3n pol\u00edticamente conservadora que ha llevado al estado a los tribunales por otros asuntos. La gobernadora Kim Reynolds pidi\u00f3 recientemente a Ostergren que ayudara a representar al estado en los esfuerzos por restringir el aborto en Iowa mediante una legislaci\u00f3n anterior a la decisi\u00f3n del Tribunal Supremo de EE.UU. del 24 de junio de anular el caso Roe contra Wade.<\/p>\n<p>Ostergren tambi\u00e9n ha presentado una demanda para impugnar los requisitos de equilibrio de g\u00e9nero para los miembros de la Comisi\u00f3n Estatal de Nombramientos Judiciales.<\/p>\n<p>La ciudad a\u00fan no ha respondido a la demanda. La abogada de la ciudad, Vanessa Chavez, no pudo ser contactada para hacer comentarios.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"holaa-976572326\" class=\"holaa-after-content holaa-entity-placement\" style=\"margin-top: 2px;margin-bottom: 2px;margin-left: auto;margin-right: auto;text-align: center;\"><div class=\"holaa-adlabel\">Advertisements<\/div><a data-no-instant=\"1\" href=\"https:\/\/www.auditor.iowa.gov\/about-us\" rel=\"noopener\" class=\"a2t-link\" aria-label=\"Davenport MBS26007_Spanish Fund for States Ads 300x250_F\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg\" alt=\"\"  srcset=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F.jpg 1250w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-300x250.jpg 300w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1024x854.jpg 1024w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-768x640.jpg 768w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-696x580.jpg 696w, https:\/\/holaamericanews.com\/wp-content\/uploads\/2026\/07\/Davenport-MBS26007_Spanish-Fund-for-States-Ads-300x250_F-1068x890.jpg 1068w\" sizes=\"(max-width: 1250px) 100vw, 1250px\" width=\"300\" height=\"250\"  style=\"display: inline-block;\" \/><\/a><\/div>","protected":false},"excerpt":{"rendered":"<p>Por Clark Kauffman, Iowa Capital Dispatch Un hombre de Cedar Rapids est\u00e1 demandando a la ciudad y al alcalde por una disposici\u00f3n que exige que cinco miembros de la Junta [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":19394,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[11],"tags":[2404],"translation":{"provider":"WPGlobus","version":"3.0.2","language":"es","enabled_languages":["en","es"],"languages":{"en":{"title":true,"content":true,"excerpt":false},"es":{"title":true,"content":true,"excerpt":false}}},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"{:en}By Clark Kauffman, Iowa Capital Dispatch A Cedar Rapids man is suing the city and mayor over an ordinance that requires five members of the police department\u2019s Citizen Review Board to be people of color. Kevin Wymore, a retired public health analyst, alleges that in February 2021, the City of Cedar Rapids adopted an ordinance\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Hola Iowa\"\/>\n\t<meta name=\"google-site-verification\" content=\"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"{:en}Hola America News{:}{:es}Hola America News{:}\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva | Hola America News\" \/>\n\t\t<meta property=\"og:description\" content=\"{:en}By Clark Kauffman, Iowa Capital Dispatch A Cedar Rapids man is suing the city and mayor over an ordinance that requires five members of the police department\u2019s Citizen Review Board to be people of color. Kevin Wymore, a retired public health analyst, alleges that in February 2021, the City of Cedar Rapids adopted an ordinance\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2022\/07\/foto-1-5.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2022\/07\/foto-1-5.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-07-14T20:08:24+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-07-15T17:41:35+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@HolaAmericaNews\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva | Hola America News\" \/>\n\t\t<meta name=\"twitter:description\" content=\"{:en}By Clark Kauffman, Iowa Capital Dispatch A Cedar Rapids man is suing the city and mayor over an ordinance that requires five members of the police department\u2019s Citizen Review Board to be people of color. Kevin Wymore, a retired public health analyst, alleges that in February 2021, the City of Cedar Rapids adopted an ordinance\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/holaamericanews.com\/wp-content\/uploads\/2022\/07\/foto-1-5.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#article\",\"name\":\"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\\u00f3n de los miembros de la junta directiva | Hola America News\",\"headline\":\"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\\u00f3n de los miembros de la junta directiva\",\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/foto-1-5.jpg\",\"width\":1024,\"height\":683,\"caption\":\"Justice Scales and books and wooden gavel\"},\"datePublished\":\"2022-07-14T15:08:24-05:00\",\"dateModified\":\"2022-07-15T12:41:35-05:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#webpage\"},\"articleSection\":\"Hola Iowa, Iowa Capital Dispatch, Espa\\u00f1ol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"position\":2,\"name\":\"Latest News\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"position\":3,\"name\":\"Hola Iowa\",\"item\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#listItem\",\"name\":\"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\\u00f3n de los miembros de la junta directiva\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/#listItem\",\"name\":\"Latest News\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#listItem\",\"position\":4,\"name\":\"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\\u00f3n de los miembros de la junta directiva\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/category\\\/latest-news\\\/hola-iowa\\\/#listItem\",\"name\":\"Hola Iowa\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\",\"name\":\"Hola America News\",\"description\":\"The Midwest's Latino News Source\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"telephone\":\"+13097215693\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HolaAmerica-News-web-logo.png\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#organizationLogo\",\"width\":1000,\"height\":800},\"image\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/holaamerica\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/\",\"name\":\"Hola Iowa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Hola Iowa\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#webpage\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/\",\"name\":\"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\\u00f3n de los miembros de la junta directiva | Hola America News\",\"description\":\"{:en}By Clark Kauffman, Iowa Capital Dispatch A Cedar Rapids man is suing the city and mayor over an ordinance that requires five members of the police department\\u2019s Citizen Review Board to be people of color. Kevin Wymore, a retired public health analyst, alleges that in February 2021, the City of Cedar Rapids adopted an ordinance\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/author\\\/hola-iowa\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/foto-1-5.jpg\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#mainImage\",\"width\":1024,\"height\":683,\"caption\":\"Justice Scales and books and wooden gavel\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\\\/#mainImage\"},\"datePublished\":\"2022-07-14T15:08:24-05:00\",\"dateModified\":\"2022-07-15T12:41:35-05:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/\",\"name\":\"{:en}Hola America News{:}{:es}Hola America News{:}\",\"description\":\"The Midwest's Latino News Source\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/holaamericanews.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva | Hola America News","description":"{:en}By Clark Kauffman, Iowa Capital Dispatch A Cedar Rapids man is suing the city and mayor over an ordinance that requires five members of the police department\u2019s Citizen Review Board to be people of color. Kevin Wymore, a retired public health analyst, alleges that in February 2021, the City of Cedar Rapids adopted an ordinance","canonical_url":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"m7ei7MHIrIAJKgJCB-dhRHjidvMGDMt9VLZZUS8PfBM","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#article","name":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva | Hola America News","headline":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva","author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2022\/07\/foto-1-5.jpg","width":1024,"height":683,"caption":"Justice Scales and books and wooden gavel"},"datePublished":"2022-07-14T15:08:24-05:00","dateModified":"2022-07-15T12:41:35-05:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#webpage"},"isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#webpage"},"articleSection":"Hola Iowa, Iowa Capital Dispatch, Espa\u00f1ol"},{"@type":"BreadcrumbList","@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/holaamericanews.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","position":2,"name":"Latest News","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","position":3,"name":"Hola Iowa","item":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/","nextItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#listItem","name":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva"},"previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/#listItem","name":"Latest News"}},{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#listItem","position":4,"name":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva","previousItem":{"@type":"ListItem","@id":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/#listItem","name":"Hola Iowa"}}]},{"@type":"Organization","@id":"https:\/\/holaamericanews.com\/es\/#organization","name":"Hola America News","description":"The Midwest's Latino News Source","url":"https:\/\/holaamericanews.com\/es\/","telephone":"+13097215693","logo":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2023\/03\/HolaAmerica-News-web-logo.png","@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#organizationLogo","width":1000,"height":800},"image":{"@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#organizationLogo"},"sameAs":["https:\/\/www.instagram.com\/holaamerica"]},{"@type":"Person","@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author","url":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/","name":"Hola Iowa","image":{"@type":"ImageObject","@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/78dea38389dec3a934b29c1aedff8ce6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Hola Iowa"}},{"@type":"WebPage","@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#webpage","url":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/","name":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva | Hola America News","description":"{:en}By Clark Kauffman, Iowa Capital Dispatch A Cedar Rapids man is suing the city and mayor over an ordinance that requires five members of the police department\u2019s Citizen Review Board to be people of color. Kevin Wymore, a retired public health analyst, alleges that in February 2021, the City of Cedar Rapids adopted an ordinance","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/holaamericanews.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#breadcrumblist"},"author":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"creator":{"@id":"https:\/\/holaamericanews.com\/es\/author\/hola-iowa\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2022\/07\/foto-1-5.jpg","@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#mainImage","width":1024,"height":683,"caption":"Justice Scales and books and wooden gavel"},"primaryImageOfPage":{"@id":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/#mainImage"},"datePublished":"2022-07-14T15:08:24-05:00","dateModified":"2022-07-15T12:41:35-05:00"},{"@type":"WebSite","@id":"https:\/\/holaamericanews.com\/es\/#website","url":"https:\/\/holaamericanews.com\/es\/","name":"{:en}Hola America News{:}{:es}Hola America News{:}","description":"The Midwest's Latino News Source","inLanguage":"es-ES","publisher":{"@id":"https:\/\/holaamericanews.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"{:en}Hola America News{:}{:es}Hola America News{:}","og:type":"article","og:title":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva | Hola America News","og:description":"{:en}By Clark Kauffman, Iowa Capital Dispatch A Cedar Rapids man is suing the city and mayor over an ordinance that requires five members of the police department\u2019s Citizen Review Board to be people of color. Kevin Wymore, a retired public health analyst, alleges that in February 2021, the City of Cedar Rapids adopted an ordinance","og:url":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/","og:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2022\/07\/foto-1-5.jpg","og:image:secure_url":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2022\/07\/foto-1-5.jpg","og:image:width":1024,"og:image:height":683,"article:published_time":"2022-07-14T20:08:24+00:00","article:modified_time":"2022-07-15T17:41:35+00:00","article:publisher":"https:\/\/www.facebook.com\/HolaAmericaNews","twitter:card":"summary","twitter:site":"@HolaAmericaNews","twitter:title":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva | Hola America News","twitter:description":"{:en}By Clark Kauffman, Iowa Capital Dispatch A Cedar Rapids man is suing the city and mayor over an ordinance that requires five members of the police department\u2019s Citizen Review Board to be people of color. Kevin Wymore, a retired public health analyst, alleges that in February 2021, the City of Cedar Rapids adopted an ordinance","twitter:image":"https:\/\/holaamericanews.com\/wp-content\/uploads\/2022\/07\/foto-1-5.jpg"},"aioseo_meta_data":{"post_id":"19399","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-03-28 17:37:14","updated":"2026-01-28 10:32:20","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/\" title=\"Latest News\">Latest News<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/\" title=\"Hola Iowa\">Hola Iowa<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tUna demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/holaamericanews.com\/es"},{"label":"Latest News","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/"},{"label":"Hola Iowa","link":"https:\/\/holaamericanews.com\/es\/category\/latest-news\/hola-iowa\/"},{"label":"Una demanda denuncia que Cedar Rapids discrimina a los blancos en la elecci\u00f3n de los miembros de la junta directiva","link":"https:\/\/holaamericanews.com\/es\/lawsuit-alleges-cedar-rapids-discriminates-against-whites-in-choosing-board-members\/"}],"_links":{"self":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/19399"}],"collection":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/comments?post=19399"}],"version-history":[{"count":0,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/posts\/19399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media\/19394"}],"wp:attachment":[{"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/media?parent=19399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/categories?post=19399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/holaamericanews.com\/es\/wp-json\/wp\/v2\/tags?post=19399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}